{"id":215312,"date":"2023-11-02T12:28:42","date_gmt":"2023-11-02T11:28:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=215312"},"modified":"2023-11-02T12:29:41","modified_gmt":"2023-11-02T11:29:41","slug":"lappuntamento-con-una-donna-si-trasforma-in-un-incubo-sequestrato-e-seviziato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lappuntamento-con-una-donna-si-trasforma-in-un-incubo-sequestrato-e-seviziato\/","title":{"rendered":"L&#8217;appuntamento con una donna si trasforma in un incubo, sequestrato e seviziato"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Un&#8217;uscita a due, un appuntamento galante con una donna, si \u00e8 trasformato in un vero e proprio incubo. Vittima un ragazzo della provincia di Vibo Valentia il quale dopo aver instaurato un&#8217;amicizia sui social ha deciso di incontrarla di persona. Quando <strong>lei lo ha invitato a casa<\/strong> per &#8216;proseguire la serata&#8217; \u00e8 <strong>scattata la trappola<\/strong>.<\/p>\n<p>Il giovane infatti, una volta nell\u2019appartamento <strong>si sarebbe trovato di fronte il figlio<\/strong> della donna che lo avrebbe prima <strong>stordito<\/strong> colpendolo con un <strong>bastone alla nuca<\/strong>. Poi, aiutato dalla madre, \u00e8 stato legato ad una sedia, percosso ripetutamente e seviziato con un\u2019arma da taglio che gli avrebbe procurato <strong>diversi tagli sul corpo. <\/strong><\/p>\n<p>Lo scopo, secondo quanto emerso, sarebbe stato quello di costringere la vittima a <strong>rivelare la password del bancomat<\/strong> e eventuali depositi di denaro contante presso la sua abitazione. Il giovane, minacciato di subire conseguenze pi\u00f9 gravi avrebbe ceduto.\u00a0 La donna \u00e8 stata cos\u00ec accompagnata da un altro soggetto nell\u2019abitazione della vittima dalla quale sarebbero stati asportati asportati 2.500 in contanti. Poi il passaggio al bancomat, in una filiale bancaria di Vibo, dove la donna ha prelevato altro denaro.<\/p>\n<p>Solo dopo il giovane sarebbe stato liberato dai tre che lo hanno anche minacciato di non raccontare nulla dell\u2019accaduto per evitare ritorsioni.<\/p>\n<p>Sono stati i carabinieri per\u00f2, a scoprire tutto quando, nel corso di un servizio notturno, hanno notato il giovane che ha chiesto loro soccorso ed \u00e8 scattata la denuncia. Subito sono partite le verifiche su quanto raccontato dalla vittima e i militari sono passati a visionare i filmati delle telecamere di videosorveglianza e i profili social dei presunti autori del sequestro di persona e della brutale aggressione.<\/p>\n<p>La Procura di Vibo ha emesso un decreto di fermo, eseguito dai carabinieri, nei confronti dei tre soggetti (trasferiti in carcere) che dovranno rispondere di sequestro di persona, porto di armi, rapina e lesioni con <strong>l\u2019aggravante della crudelt\u00e0<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Un&#8217;uscita a due, un appuntamento galante con una donna, si \u00e8 trasformato in un vero e proprio incubo. Vittima un ragazzo della provincia di Vibo Valentia il quale dopo aver instaurato un&#8217;amicizia sui social ha deciso di incontrarla di persona. Quando lei lo ha invitato a casa per &#8216;proseguire la serata&#8217; \u00e8 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":212719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-215312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=215312"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/212719"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=215312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=215312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=215312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}