{"id":215492,"date":"2023-11-03T20:00:24","date_gmt":"2023-11-03T19:00:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=215492"},"modified":"2023-11-03T19:30:09","modified_gmt":"2023-11-03T18:30:09","slug":"citta-unica-il-comitato-cittadino-incontra-i-commissari-prefettizi-in-comune","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/citta-unica-il-comitato-cittadino-incontra-i-commissari-prefettizi-in-comune\/","title":{"rendered":"Citt\u00e0 unica, il comitato cittadino incontra i commissari prefettizi in Comune"},"content":{"rendered":"<p>RENDE (CS) &#8211; &#8220;In data odierna una rappresentanza del Comitato Cittadino di Rende costituito in merito alla questione della <strong>Citt\u00e0 Unica Cosenza-Rende-Castrolibero<\/strong>, \u00e8 stata ricevuta in Municipio dal dott. Santi Giuffr\u00e8, Presidente della Commissione Prefettizia che oggi governa la citt\u00e0 di Rende. Al dott. Giuffr\u00e8, che ci ha accolti con estrema cordialit\u00e0, abbiamo <strong>espresso le nostre considerazioni sulla Proposta di Legge Regionale, illustrato il percorso da noi avviato<\/strong> con la prima Assemblea Popolare e consegnato il documento approvato nel corso della stessa, contenente anche la relazione tecnico-giuridica del prof. D&#8217;Ignazio. Al termine della riunione abbiamo ringraziato il dott. Giuffr\u00e8 per la disponibilit\u00e0 all&#8217;ascolto e la particolare sensibilit\u00e0 dimostrata verso la nostra comunit\u00e0 cittadina che i Commissari sono chiamati in questo momento a rappresentare&#8221;.<\/p>\n<h3><strong><u>I componenti<\/u>:<\/strong><\/h3>\n<p>Francesco Adamo, Mario Bartucci, Maurizio Bonofiglio, Alessandro Caia, Amerigo Castiglione, Marinella Castiglione, Pasquale Costabile, Francesca Cufone, Emilio De Bartolo, Clelio Gelsomino, Pierpaolo Iantorno, Massimo La Deda, Fabio Liparoti, Michele Morrone, Innocenzo Palazzo, Lorenzo Principe, Sandro Principe, Mario Rausa, Carlo Scola, Domenico Talarico, Francesco Tenuta, Sergio Tursi Prato, Valdo Vercillo, in rappresentanza di: RendeS\u00ec, Rende l\u2019Idea, Missione Rende, La Primavera di Rende, InnovaRende, AttivaRende, Federazione Riformista di Rende, Laboratorio Politico \u201cCarlo Rosselli\u201d, Partito Socialista Italiano di Rende, IdM Rende, Movimento Civico Rende, Aria Nuova-Rende Centro Storico, Associazione La Fenice-Centro Storico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; &#8220;In data odierna una rappresentanza del Comitato Cittadino di Rende costituito in merito alla questione della Citt\u00e0 Unica Cosenza-Rende-Castrolibero, \u00e8 stata ricevuta in Municipio dal dott. Santi Giuffr\u00e8, Presidente della Commissione Prefettizia che oggi governa la citt\u00e0 di Rende. Al dott. Giuffr\u00e8, che ci ha accolti con estrema cordialit\u00e0, abbiamo espresso le [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":197969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-215492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=215492"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/197969"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=215492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=215492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=215492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}