{"id":215524,"date":"2023-11-04T10:32:52","date_gmt":"2023-11-04T09:32:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=215524"},"modified":"2023-11-04T10:32:52","modified_gmt":"2023-11-04T09:32:52","slug":"roseto-capo-spulico-incontro-con-la-comunita-per-costruire-un-comune-ad-esclusione-zero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/roseto-capo-spulico-incontro-con-la-comunita-per-costruire-un-comune-ad-esclusione-zero\/","title":{"rendered":"Roseto Capo Spulico: incontro con la comunit\u00e0 per costruire un &#8216;Comune ad Esclusione Zero&#8217;"},"content":{"rendered":"<p>ROSETO CAPO SPULICO (CS) &#8211; Dopo la bellissima esperienza vissuta in occasione del Festival &#8220;<strong>Innesti di Futuro&#8221;<\/strong>, l&#8217;Amministrazione Comunale di Roseto Capo Spulico e la sua vivace Comunit\u00e0 \u00e8 pronta a rimettersi al lavoro sul Progetto <strong>&#8220;Roseto Comune ad Esclusione Zero&#8221;,<\/strong> offrendo alla Cittadinanza nuovi &#8220;<strong>Strumenti di Innovazione Sociale<\/strong>&#8221; attraverso due giorni ricchi di incontri di Co-progettazione e Co-programmazione insieme ai pi\u00f9 grandi esperti di welfare ed economica civile italiani.<\/p>\n<p>Questo progetto, costruito in sinergia con importanti realt\u00e0 nazionali come Fondazione Con il Sud, il Consorzio Sale della Terra, la Rete dei Piccoli Comuni del Welcome e NEXT \u2013 Nuova Economia per tutti, si pone come principale obiettivo la creazione di un sistema di welfare innovativo ed inclusivo, capace di generare lavoro e benessere sfruttando le enormi potenzialit\u00e0 ancora in parte inespresse del nostro territorio.<\/p>\n<p><strong>Oggi e domani, l\u2019Antico Granaio ospiter\u00e0 una intensa due giorni di lavoro<\/strong>, attraverso i quali i Cittadini, gli operatori economici, il mondo dell&#8217;associazionismo e del terzo settore potranno ottenere informazioni utili e strumenti operativi per comprendere, costruire, avviare nuovi percorsi imprenditoriali e generare nuova economia valorizzando competenze e professionalit\u00e0 a beneficio dell&#8217;intera Comunit\u00e0 locale.<\/p>\n<p>Il primo appuntamento \u00e8 fissato per <strong>questo pomeriggio<\/strong> alle <strong>ore 16.00<\/strong>, con il focus tra i Sindaci dell\u2019Ampliamento SAI e la Rete dei Piccoli Comuni del Welcome sulle \u201cOpportunit\u00e0 e prospettive del Sistema di Accoglienza e Integrazione e la rete dei Comuni\u201d.<br \/>\n<strong>Domenica 5 Novembre<\/strong> alle ore 9.30, l\u2019incontro di Co-Progettazione \u201cCittadinanza (che si) Attiva\u201d per una Roseto ad Esclusione Zero. Nella stessa giornata, alle ore 16.30,l\u2019incontro pubblico su \u201cBeni Comuni e Cittadini Attivi. Amministrazione Condivisa, Co-programmazione e Co-progettazione\u201d. Grazie ad autorevoli contributi al tavolo dei relatori, verranno affrontati temi strettamente legati alla crescita e allo sviluppo del territorio, partendo dal progetto<strong> \u201cRoseto Capo Spulico: Comune ad Esclusione Zero\u201d,<\/strong> sperimentato nella realt\u00e0 locale di Roseto Capo Spulico.<\/p>\n<p>Sar\u00e0 presente all&#8217;evento un ricco e autorevole parterre, che aiuter\u00e0 la Cittadinanza nel percorso progettuale. Saranno presenti al tavolo dei relatori moderato dalla giornalista Gabriella Debora Giorgione, il Sindaco Rosanna Mazzia, Angelo Moretti, Referente nazionale della Rete per i Piccoli Comuni del Welcome; Fabio Garrisi, Referente ufficio co-progettazione e gare Sale della Terra e direttore Sale della Terra Salento; Pasquale Bonasora, Presidente di Labsus-Laboratorio per la sussidiariet\u00e0; Luciano Gallo, Referente contratti pubblici e innovazione sociale, diritto del Terzo settore di ANCI Emilia-Romagna;<br \/>\nConclude S.E. Mons. Francesco Savino, Vescovo Diocesi Cassano allo Jonio.<\/p>\n<p>L\u2019incontro pubblico Beni comuni e cittadini attivi, sar\u00e0 l\u2019occasione anche per presentare Welfare meridiano, la monografia di Angelo Moretti, edita da Rubbettino. Non ho mai avuto particolari simpatie per le forme organizzative del servizio sociale \u2013 dice Moretti nel suo libro \u2013 Da quando ho iniziato il mio impegno sociale, mi interessava, e mi interessa ancora oggi, il \u201cfatto concreto\u201d: aiutare con ogni mezzo chi \u00e8 in una condizione di fragilit\u00e0 e apprendere continuamente da chi attraversa una condizione di fragilit\u00e0 nuove visioni sul senso dell\u2019esistere e sulle forme della vita.<\/p>\n<p>&#8220;Riprendiamo da dove ci eravamo lasciati, ma il solco nel quale ci muoviamo \u00e8 sempre lo stesso &#8211; ha affermato il Sindaco Mazzia &#8211; Vogliamo esplorare tutte le strade, provare ad accumulare quante pi\u00f9 informazioni possibili, metterci alla prova su ambiti diversi per raggiungere un obiettivo comune. In questa due giorni cos\u00ec intensa parleremo di \u201cwelfare\u201d che significa tante cose, ma prima di tutto, secondo me, vuol dire \u201cstare insieme\u201d. Parleremo di come stando insieme si pu\u00f2 accrescere il benessere della nostra Comunit\u00e0 e creare sviluppo facendo coprogettazione e amministrazione condivisa. Condivideremo questo percorso con i maggiori esperti in Italia di questo settore e con il nostro Vescovo, che sulle cose importanti non manca mai. Non prendete impegni domenica, sar\u00e0 una giornata importante per Roseto Capo Spulico e per l&#8217;intero territorio&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-215526 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1.png\" alt=\"roseto 4-5 novembre (1)\" width=\"514\" height=\"734\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1.png 700w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-210x300.png 210w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-717x1024.png 717w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-768x1097.png 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-1075x1536.png 1075w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-1434x2048.png 1434w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-150x214.png 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-300x429.png 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-696x994.png 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-1068x1526.png 1068w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-1920x2743.png 1920w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/roseto-4-5-novembre-1-294x420.png 294w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSETO CAPO SPULICO (CS) &#8211; Dopo la bellissima esperienza vissuta in occasione del Festival &#8220;Innesti di Futuro&#8221;, l&#8217;Amministrazione Comunale di Roseto Capo Spulico e la sua vivace Comunit\u00e0 \u00e8 pronta a rimettersi al lavoro sul Progetto &#8220;Roseto Comune ad Esclusione Zero&#8221;, offrendo alla Cittadinanza nuovi &#8220;Strumenti di Innovazione Sociale&#8221; attraverso due giorni ricchi di incontri [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":211784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-215524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=215524"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/211784"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=215524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=215524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=215524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}