{"id":215933,"date":"2023-11-08T15:43:29","date_gmt":"2023-11-08T14:43:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=215933"},"modified":"2023-11-08T15:44:22","modified_gmt":"2023-11-08T14:44:22","slug":"montalto-uffugo-domani-screening-gratuiti-delludito-per-tutti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/montalto-uffugo-domani-screening-gratuiti-delludito-per-tutti\/","title":{"rendered":"Montalto Uffugo, domani screening gratuiti dell&#8217;udito per tutti"},"content":{"rendered":"<p>MONTALTO UFFUGO (CS) &#8211; Il<strong> convegno \u201cAscolta Montalto\u201d,<\/strong> <strong>organizzato dall\u2019assessorato ai Servizi Sociali, e clinica audiologica M.A.X.O.<\/strong> si terr\u00e0 oggi, <strong>mercoled\u00ec 8 novembre alle ore 17:00<\/strong> presso la delegazione comunale di via Benedetto Croce<\/p>\n<p>Sensibilizzare all\u2019importanza della prevenzione ed alla cura dell\u2019udito \u00e8 il fine del convegno organizzato dall\u2019assessorato ai Servizi Sociali del Comune di Montalto Uffugo, guidato da Franco Ferro, insieme alla clinica audiologica Maxo di Cosenza del Dottor G. Blasi.<\/p>\n<p><strong>Parteciperanno all\u2019incontro<\/strong>, moderato dalla giornalista Manuela Molinaro, il sindaco di Montalto Uffugo, Pietro Caracciolo, l\u2019assessore Franco Ferro, la responsabile Francesca Lauria, Responsabile dell\u2019Ufficio Servizi Sociali del Comune, Massimo Ferraro, Presidente dell\u2019Associazione Luce, Paola Ambrosio, Presidente di CIF Calabria e Pasqualina Florio, Referente di AINSPED provincia di Cosenza.<\/p>\n<p>Dopo l\u2019introduzione del presidente di Insieme ODV, Antonio Chiappetta, prenderanno la parola i relatori: dott. Giuseppe Blasi per la Clinica audiologica MAXO Cosenza; dott.ssa Carmen Romano, in qualit\u00e0 di Garante dei diritti dei disabili del Comune di Montalto Uffugo; Nicola Perri, Consigliere Ente Nazionale Sordi, sezione provinciale di Cosenza.<\/p>\n<p><strong>Il convegno sar\u00e0 tradotto nella lingua dei segni LIS<\/strong>. <strong>Gioved\u00ec 9 novembre ci sar\u00e0 invece la possibilit\u00e0 di effettuare uno screening audiometrico gratuito con prenotazione durante l\u2019evento<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-215935 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-300x186.jpg\" alt=\"convegno ascolta montalto\" width=\"300\" height=\"186\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet-356x220.jpg 356w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/FotoJet.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO UFFUGO (CS) &#8211; Il convegno \u201cAscolta Montalto\u201d, organizzato dall\u2019assessorato ai Servizi Sociali, e clinica audiologica M.A.X.O. si terr\u00e0 oggi, mercoled\u00ec 8 novembre alle ore 17:00 presso la delegazione comunale di via Benedetto Croce Sensibilizzare all\u2019importanza della prevenzione ed alla cura dell\u2019udito \u00e8 il fine del convegno organizzato dall\u2019assessorato ai Servizi Sociali del Comune di [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":215935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-215933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=215933"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/215935"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=215933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=215933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=215933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}