{"id":215966,"date":"2023-11-08T22:30:25","date_gmt":"2023-11-08T21:30:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=215966"},"modified":"2023-11-08T20:12:20","modified_gmt":"2023-11-08T19:12:20","slug":"cosenza-i-socialisti-si-lamentano-della-minoranza-troppo-superficiale-difficile-parlarci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-i-socialisti-si-lamentano-della-minoranza-troppo-superficiale-difficile-parlarci\/","title":{"rendered":"Cosenza, i socialisti si lamentano della minoranza: \u00abtroppo superficiale, difficile parlarci\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;<strong>L&#8217;interlocuzione con i colleghi di minoranza \u00e8 sempre difficile, ma diventa ancor pi\u00f9 complessa quando dimostrano superficialit\u00e0 e<\/strong> discordanza anche rispetto ai loro rappresentanti di partito ad ogni livello, anche locale. Ed, infatti, la loro \u00e8 solo una difesa a spada tratta, senza riflessione n\u00e9 attenzione agli argomenti trattati, perch\u00e9 per loro l&#8217;importante \u00e8 affermare che hanno ragione i fratelli Occhiuto a prescindere da tutto e da tutti, compreso i partiti di appartenenza. Ne prendiamo atto e con noi siamo certi lo faranno anche i cosentini senza neanche tanto struggimento&#8221;.<\/p>\n<p>E&#8217; quanto afferma <strong>il gruppo consiliare del PSI in seno al Consiglio Comunale di Cosenza, <\/strong>rispondendo &#8220;alle solite farneticazioni dei consiglieri di minoranza, noti pasdaran dei fratelli Occhiuto e per questo pronti ad arrampicarsi sugli specchi pur di giustificarne l&#8217;azione miope e di parte, penalizzante per Cosenza e la sua provincia, che alla Regione Calabria si sta portando avanti&#8221;.<\/p>\n<p>&#8220;Ed, infatti \u2013 proseguono i socialisti di Palazzo dei Bruzi \u2013 <strong>si tace sui metodi antidemocratici ed illiberali della legge Omnibus<\/strong> approvata a Palazzo Campanella (da non confondere con la proposta di legge sulla costituzione del Comune Unico per come aveva fatto l&#8217;on. De Francesco) che, modificando il comma 3 dell&#8217;art. 5 della legge n.15\/2006, ha estromesso i Comuni da ogni processo decisionale lasciando alla Regione Calabria la decisione autonoma di cancellare singoli Comuni per istituirne uno nuovo. Si preferisce, invece di entrare nel merito delle questioni sollevate, parlare genericamente di fantasmi e di ambiguit\u00e0 forse perch\u00e9, come recita un vecchio detto: A gatta da dispensa come fa pensa&#8221;.<\/p>\n<p>&#8220;A voler tacere, poi \u2013 concludono i consiglieri del PSI &#8211; dell&#8217;arrampicata con scivolo finale rispetto alle esternazioni riguardanti <strong>la sentenza del Tar sul nuovo ospedale di Cosenza,<\/strong> dove addirittura si arriva a prevedere &#8216;che anche quando l&#8217;interesse del Comune di Cosenza potr\u00e0 considerarsi &#8220;attuale&#8221; a termini di legge, ogni eventuale ostracismo dell&#8217;attuale Sindaco si riveler\u00e0 comunque vano&#8217;.<\/p>\n<p>Anticipano, quindi, &#8211; precisano i socialisti &#8211; l&#8217;eventuale prossima sentenza del TAR e ribadiscono, bont\u00e0 loro, una smisurata fiducia nell&#8217;operato dei fratelli Occhiuto che per intanto stanno continuando a punire Cosenza. Tant&#8217;\u00e8 che, dopo lo sventramento di Viale Parco ad opera di Mario, Roberto ha completato l&#8217;opera <strong>definanziando la metropolitana leggera<\/strong>. Ora si tenta di assestare il colpo finale alla nostra citt\u00e0, <strong>allungando i tempi procedurali del nuovo ospedale di Cosenz<\/strong>a per non realizzarlo. In tutto ci\u00f2 neanche l&#8217;ombra di un anelito di pudore e imbarazzo. Evidentemente hanno stomaci di ferro, ma noi non li invidiamo per questo!&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;L&#8217;interlocuzione con i colleghi di minoranza \u00e8 sempre difficile, ma diventa ancor pi\u00f9 complessa quando dimostrano superficialit\u00e0 e discordanza anche rispetto ai loro rappresentanti di partito ad ogni livello, anche locale. Ed, infatti, la loro \u00e8 solo una difesa a spada tratta, senza riflessione n\u00e9 attenzione agli argomenti trattati, perch\u00e9 per loro l&#8217;importante [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":188483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-215966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=215966"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/215966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/188483"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=215966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=215966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=215966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}