{"id":216532,"date":"2023-11-14T15:40:51","date_gmt":"2023-11-14T14:40:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=216532"},"modified":"2023-11-14T15:41:49","modified_gmt":"2023-11-14T14:41:49","slug":"lannunziata-di-cosenza-e-il-peggior-ospedale-ditalia-ultimo-in-classifica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lannunziata-di-cosenza-e-il-peggior-ospedale-ditalia-ultimo-in-classifica\/","title":{"rendered":"\u00abL&#8217;Annunziata di Cosenza \u00e8 il peggior ospedale d&#8217;Italia: ultimo in classifica\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;<strong>L\u2019AGENAS ha pubblicato la nuova classifica degli ospedali d\u2019Italia<\/strong>. Per il secondo anno, di seguito, salgono sul podio, di migliori ospedali d&#8217;Italia, l\u2019Istituto Clinico Humanitas di Rozzano e l&#8217;Azienda Ospedaliera Universitaria delle Marche. I due ospedali, il primo privato ed il secondo pubblico, figurano, infatti, al top nella classifica del Programma Nazionale Esiti (Pne), che \u00a0l&#8217;Agenas ha sviluppato su mandato del Ministero della Salute. Di contro, al primo posto, nella sezione dei peggiori ospedali italiani, figura, ancora e esattamente, l\u2019Ospedale civile dell\u2019Annunziata di Cosenza.\u00a0<b>Quindi, l\u2019Ospedale di Cosenza \u00e8 il peggiore ospedale italiano &#8211; <\/b>scrive in una nota <b>Giuseppe Ciacco<\/b><br \/>\n<b>Consigliere comunale della citt\u00e0 di Cosenza-<\/b>; \u00e8 l\u2019ospedale\u00a0con le performance pi\u00f9 basse. Sennonch\u00e8,\u00a0da <strong>Wikipedia<\/strong>, si legge che l\u2019attuale Presidente della Giunta regionale della Calabria, nonch\u00e9 Commissario ad acta della sanit\u00e0, <strong>\u00e8 nato a Cosenza<\/strong> ed \u00e8 il fratello minore di colui il quale, per dieci anni, dal 2011 al 2021 \u00e8 stato il sindaco di Cosenza.\u00a0<strong>Quindi, il Governatore della Calabria \u00e8 figlio verace \u00a0della citt\u00e0 di Cosenza<\/strong>.\u00a0E allora, \u00e8 paradossale che proprio l\u2019Ospedale della citt\u00e0, nella quale \u00e8 nato e, verosimilmente, vive il Governatore &#8211; Commissario ad acta, nella quale il di lui fratello \u00e8 stato, per dieci anni, Sindaco, sia, maledettamente, il fanalino di coda nella classifica nazionale. E\u2019 una vera e propria contraddizione in termini.<\/p>\n<p><strong>Se un Governatore, per di pi\u00f9 e per giunta, Commissario ad acta della sanit\u00e0 &#8211; <\/strong>continua Ciacco <strong>&#8211; non \u00e8 in grado di risollevare, dall\u2019ultimo posto in classifica, l\u2019Ospedale della propria citt\u00e0, vuol dire allora, che l\u2019inettitudine gestionale \u00a0e l\u2019incapacit\u00e0 politica hanno raggiunto vette stratosferiche &#8211; continua il consigliere &#8211; <\/strong>che mettono in gravissima sofferenza la stessa esigibilit\u00e0 del diritto alla salute di migliaia e migliaia di cittadini. La collocazione dell\u2019Ospedale di Cosenza all\u2019ultimo posto della classifica nazionale <strong>\u00e8\u00a0il timbro di fabbrica di un ceto politico<\/strong>, che, sul terreno del governo della sanit\u00e0 &#8211; ma, per la verit\u00e0, non solo su questo terreno &#8211;\u00a0<strong>ha inappellabilmente e disastrosamente fallito<\/strong>. Ed \u00e8 un fallimento ascrivibile, esclusivamente, alla classe dirigente. E\u00a0<strong>nessuno si azzardi a scaricare eventuali responsabilit\u00e0 \u00a0sulla classe medica e infermieristica dell\u2019Annunziata<\/strong>. I medici e gli infermieri dell\u2019Ospedale di Cosenza costituiscono un meraviglioso esercito, di uomini e donne in carne ossa, dalle straordinarie \u00a0qualit\u00e0 professionali, che quotidianamente, con esemplare abnegazione, stanno in trincea, nonostante le acute criticit\u00e0 strutturali di uno stabilimento ospedaliero, la cui decadenza \u00e8 in caduta libera.<\/p>\n<p>E\u00a0<strong>la decadenza dell\u2019Annunziata \u00e8 figlia legittima del Commissario ad acta e del management aziendale, complice \u00a0e sodale del primo<\/strong>. La decadenza \u00e8 figlia legittima di scelte errate, di imperdonabili ritardi, di dannose inadempienze, di torbidi intrighi.\u00a0<strong>E sotto questa profilo, \u00e8 e continua a essere, terribilmente emblematica la vicenda della Centrale di sterilizzazione dell\u2019Azienda ospedaliera di Cosenza<\/strong>. Le Centrali di Sterilizzazione sono il cuore del sistema ospedaliero. Ebbene,\u00a0<strong>la centrale di sterilizzazione dell\u2019Azienda ospedaliera di Cosenza<\/strong>, al di l\u00e0 di qualche partigiana difesa d\u2019ufficio,\u00a0<strong>\u00e8 allo stato attuale una micidiale fonte di pericolo<\/strong>: lo attestano, inoppugnabilmente,\u00a0<strong>i verbali dei sopralluoghi<\/strong> <strong>effettuati lo scorso mese di febbraio<\/strong>, cio\u00e8 a dire 9 mesi fa. Quei verbali ricostruiscono\u00a0<strong>una situazione spaventosamente allarmante<\/strong>, fra l\u2019altro, datata nel tempo. E quei verbali certificano che <strong>tutte\u00a0le apparecchiature di processo sono obsolete<\/strong>\u00a0e non in linea con le attuali normative: ed \u00e8 vero, perch\u00e9 si tratta di strumenti acquistati\u00a0<strong>oltre 20 anni fa<\/strong>\u00a0e per i quali, sul mercato, oggi non si rinvengono neppure\u00a0<strong>i pezzi di ricambio<\/strong>.<\/p>\n<p>E quei verbali certificano che l\u2019impianto elettrico non \u00e8 a norma; che non \u00e8 stata eseguita nessuna analisi sulla composizione del materiale della controsoffittatura: \u00e8 possibile, quindi, che in quei pannelli,\u00a0<strong>ci sia anche amianto<\/strong>; che le zone filtro delle aree di lavoro \u00a0non sono a norma, secondo le linee guida dell\u2019OMS; che le porte tagliafuoco sono presenti soltanto \u00a0sul \u00a0perimetro esterno della Centrale: il che significa che, all\u2019interno della centrale, se divampa un incendio,\u00a0<strong>c\u2019\u00e8 il rischio, serio e concreto, di morire carbonizzati<\/strong>. Ci\u00f2 nonostante, da quel sopralluogo sono\u00a0<strong>trascorsi oltre 9 mesi e la situazione non \u00e8 cambiata nemmeno di una virgola<\/strong>. Addirittura a quanto pare, da una parte, <strong>l\u2019Azienda che gestisce<\/strong>\u00a0al momento il processo di sterilizzazione, \u00a0avrebbe, maldestramente e irresponsabilmente, \u00a0dichiarato\u00a0che <strong>il servizio pu\u00f2 tranquillamente\u00a0continuare a essere erogato in queste attuali condizioni<\/strong>\u00a0e, dall\u2019altra parte, <strong>il\u00a0progetto<\/strong> esecutivo e definitivo dei lavori di manutenzione, \u00a0starebbe\u00a0<strong>stagnando<\/strong>\u00a0nei cassetti della scrivania del Commissario dell\u2019Azienda ospedaliera.<\/p>\n<p>Della serie,\u00a0<strong>tutti<\/strong>, il Commissario ad acta alla sanit\u00e0, il Commissario dell\u2019Azienda ospedaliera, i tecnici dei servizi ospedalieri, i tecnici dell\u2019azienda ospedaliera, il consulente dell\u2019azienda ospedaliera, il gestore del servizio, \u00a0<strong>sanno e, tutti, ostinatamente accaniti, a declinare \u00a0una scandalosa, scellerata \u00a0e intollerabile inerzia<\/strong>. E nel frattempo &#8211; conclude il consigliere &#8211; la centrale di sterilizzazione dell\u2019Azienda ospedaliera di Cosenza, continua a versare in una condizione di <strong>degradante sfacelo<\/strong>, che pone \u00a0in grave pericolo l\u2019incolumit\u00e0 pubblica.\u00a0<strong>Ecco perch\u00e9, poi, l\u2019Ospedale di Cosenza \u00e8 l\u2019ultimo nella classifica nazionale<\/strong>. Che miserabile vergogna&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;L\u2019AGENAS ha pubblicato la nuova classifica degli ospedali d\u2019Italia. Per il secondo anno, di seguito, salgono sul podio, di migliori ospedali d&#8217;Italia, l\u2019Istituto Clinico Humanitas di Rozzano e l&#8217;Azienda Ospedaliera Universitaria delle Marche. I due ospedali, il primo privato ed il secondo pubblico, figurano, infatti, al top nella classifica del Programma Nazionale Esiti [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":206474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,28],"tags":[19],"class_list":["post-216532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/216532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=216532"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/216532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/206474"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=216532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=216532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=216532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}