{"id":21661,"date":"2013-05-02T13:06:51","date_gmt":"2013-05-02T11:06:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21661"},"modified":"2023-01-17T13:19:22","modified_gmt":"2023-01-17T12:19:22","slug":"8394-le-bancarelle-migrano-nuovamente-inaugurata-nuova-area-mercatale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8394-le-bancarelle-migrano-nuovamente-inaugurata-nuova-area-mercatale\/","title":{"rendered":"Mercato Villaggio Europa, le bancarelle migrano nuovamente"},"content":{"rendered":"<p style=\"text-align: justify;\">RENDE &#8211; Agli ambulanti non \u00e8 mai piaciuta, i frequentatori non si sono mai abituati, in poco tempo riusc\u00ec a far registrare enormi cali nel commercio.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Eppure Cavalcanti ci riprova. E&#8217; stata inaugurata questa mattina la nuova <span class=\"il\">area<\/span> <span class=\"il\">mercatale<\/span>, nella zona di Villaggio Europa. Nuova, si fa per dire, perch\u00e8 la struttura costruita da anni ma utilizzata pochissimo era gi\u00e0 stata adibita ad area mercatale sollevando le critiche di tutto l&#8217;universo che gira intorno al mercato rionale di Rende. Da quest\u2019oggi il tradizionale mercato del gioved\u00ec si \u00e8 spostato nello spazio ristrutturato, interessato nei mesi scorsi da lavori di adeguamento e di ridefinizione delle aree adibite ai venditori. Circa 164 quelli che, a seguito della graduatoria espletata dall\u2019ufficio SUAP del Comune, sono risultati assegnatari di uno spazio. Da qui a qualche settimana, inoltre, saranno assegnati ulteriori 20 posti. &#8220;La nuova <span class=\"il\">area<\/span>, &#8211; spiega il Comune di Rende in una nota &#8211; pi\u00f9 funzionale ed agevole prevede anche una serie di parcheggi ed una strada interna per l\u2019eventuale passaggio di un\u2019ambulanza&#8221; ed \u00e8 stata inaugurata dal Sindaco, Vittorio Cavalcanti assieme al Vicesindaco Emilio De Bartolo e all\u2019assessore alla Manutenzione e Polizia Municipale Luca Pizzini. Al tagli del nastro, tra gli altri, era presente anche l\u2019On. Sandro Principe insieme al parroco della Chiesa San Carlo Borromeo, Don Aldo Giovinco. &#8220;Nonostante la pioggia, &#8211; scrive il Comune in una nota &#8211; il sindaco ha effettuato un lungo giro tra gli stand e le bancarelle dei commercianti, soffermandosi a chiacchierare con molti cittadini e ambulanti che hanno dichiarato il proprio apprezzamento per la nuova collocazione&#8221;. Il Sindaco, Vittorio Cavalcanti ha espresso &#8220;compiacimento per la consegna alla citt\u00e0 di un&#8217;opera strategica che rende pi\u00f9 civile e vivibile il centro cittadino. E\u2019 importante sottolineare come il dialogo e la concertazione abbiano permesso di superare alcune criticit\u00e0 emerse con alcuni &nbsp;commercianti. Il confronto con loro \u00e8 stato totale &#8211; &nbsp;ha sottolineato il Sindaco \u2013 grazie anche al prezioso supporto del Vice Sindaco Emilio De Bartolo e dell\u2019Assessore Luca Pizzini&#8221;. La riqualificazione dell&#8217;area \u00e8 costata ai cittadini rendesi 131mila euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Agli ambulanti non \u00e8 mai piaciuta, i frequentatori non si sono mai abituati, in poco tempo riusc\u00ec a far registrare enormi cali nel commercio.<\/p>\n","protected":false},"author":22,"featured_media":21662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-21661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21661"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21662"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}