{"id":217084,"date":"2023-11-20T07:30:21","date_gmt":"2023-11-20T06:30:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=217084"},"modified":"2023-11-19T18:37:20","modified_gmt":"2023-11-19T17:37:20","slug":"calcio-aspettando-il-derby-marras-ci-teniamo-tantissimo-a-fare-bene","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/calcio-aspettando-il-derby-marras-ci-teniamo-tantissimo-a-fare-bene\/","title":{"rendered":"Calcio, aspettando il derby. Marras: \u00abci teniamo tantissimo a fare bene\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; All\u2019atteso <strong>derby del Ceravolo<\/strong> di domenica prossima manca una settimana. La sosta per gli impegni delle nazionali ha quasi <strong>moltiplicato quella tensione che accompagna tutte le gare come queste<\/strong>. Sponda Cosenza, tra un allenamento ed un altro i giocatori rossoblu hanno preso parte ad un\u2019iniziativa organizzata presso lo Store in centro citt\u00e0 ed <strong>hanno incontrato tanti tifosi<\/strong>. Sul campo, per\u00f2, la squadra ha lavorato per migliorare quegli aspetti che finora hanno funzionato meno. L&#8217;undici di <strong>Caserta<\/strong> arriva dalla vittoria casalinga contro la <strong>Reggiana<\/strong>, ma anche dopo alcune gare in cui <strong>non sempre la squadra a messo in mostra le sue potenzialit\u00e0<\/strong>.<\/p>\n<p>&#8220;Il campionato di serie B \u00e8 molto difficile ed ogni partita \u00e8 una storia a s\u00e8 &#8211; ha detto <strong>il giocatore del Cosenza, Manuel Marras<\/strong> &#8211; ogni squadra trova delle difficolt\u00e0. Sicuramente possiamo fare meglio in alcune partite, soprattutto in casa. Abbiamo sbagliato come atteggiamento&#8221;.<\/p>\n<p><strong>Catanzaro-Cosenza<\/strong>, per\u00f2, manca dal 2018 in serie C, mentre nel campionato cadetto addirittura dal 1990. Normale che l\u2019attesa sia grande: &#8220;<strong>Un derby \u00e8 sempre un derby<\/strong> &#8211; ha detto Marras &#8211; essendo di Genova conosco benissimo i derby. <strong>Sono una storia a s\u00e8<\/strong>, ma sono sempre tre punti, questo mi ha insegnato il calcio. <strong>Ci teniamo tantissimo a fare bene<\/strong>&#8220;.<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; All\u2019atteso derby del Ceravolo di domenica prossima manca una settimana. La sosta per gli impegni delle nazionali ha quasi moltiplicato quella tensione che accompagna tutte le gare come queste. Sponda Cosenza, tra un allenamento ed un altro i giocatori rossoblu hanno preso parte ad un\u2019iniziativa organizzata presso lo Store in centro citt\u00e0 ed [&hellip;]<\/p>\n","protected":false},"author":65,"featured_media":217095,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19,135],"class_list":["post-217084","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-sport","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=217084"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/217095"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=217084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=217084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=217084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}