{"id":217174,"date":"2023-11-20T17:34:39","date_gmt":"2023-11-20T16:34:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=217174"},"modified":"2023-11-20T17:34:39","modified_gmt":"2023-11-20T16:34:39","slug":"inaugurato-il-primo-tratto-della-strada-provinciale-scalea-mormanno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/inaugurato-il-primo-tratto-della-strada-provinciale-scalea-mormanno\/","title":{"rendered":"Inaugurato il primo tratto della strada provinciale Scalea-Mormanno"},"content":{"rendered":"<p>\u00abAbbiamo inaugurato questa mattin<strong>a il primo lotto funzionale della Scalea-Mormanno<\/strong>, un tratto di strada molto importante i cui lavori erano fermi da moltissimo tempo e che oggi daranno la possibilit\u00e0 non solo di poter fruire della normale viabilit\u00e0, ma anche di una maggiore transitabilit\u00e0 per finalit\u00e0 turistiche, proprio perch\u00e9 il collegamento \u00e8 fra l\u2019entroterra e il mare\u00bb: questo il commento del Presidente della Provincia Rosaria Succurro, nel corso dell<strong>\u2019inaugurazione del primo tratto della Strada Provinciale Scalea-Mormanno, i cui lavori hanno avuto un costo di 10 milioni di euro<\/strong>.<\/p>\n<p>Presenti all\u2019inaugurazione, insieme al Presidente Rosaria Succurro: Giacomo Perrotta, Sindaco di Scalea e Paolo Pappaterra, Primo Cittadino di Mormanno; il Dirigente del Settore Viabilit\u00e0 della Provincia, Ing. Gianluca Morrone; il Responsabile del Progetto, Ing. Michele Arcuri; il Collaudatore statico e tecnico-amministrativo, Ing. Settimio Gravina; e un rappresentante dell\u2019Impresa RTI CIMA COSTRUZIONI GENERALI \u2013 SESSA COSTRUZIONI, esecutrice dei lavori.<\/p>\n<p>I lavori rientrano tra quelli previsti nell&#8217;Accordo di programma quadro siglato tra Regione e Governo e di cui la Provincia \u00e8 Ente attuatore.<strong> L&#8217;intervento si sviluppa per circa 3,2 Km <\/strong>e prevede per la maggior parte l<strong>&#8216;adeguamento della strada esistente e, per un tratto di circa 300 metri, una variante con nuovo tracciato e la realizzazione di un nuovo sottopasso ferroviario.<\/strong>Inoltre l&#8217;intervento \u00e8 comprensivo di <strong>due rotatorie<\/strong>: una sulla strada statale 18, dove l&#8217;intervento ha inizio e l&#8217;altra sulla SP 9, laddove invece termina.<\/p>\n<p>\u00abSi va avanti spediti nel mantenere gli impegni presi e garantire ai cittadini di questi territori sicurezza, dignit\u00e0 e opportunit\u00e0 di sviluppo\u00bb &#8211; ha aggiunto Rosaria Succurro, sottolineando che \u00abcome ci siamo detti con i Sindaci Perrotta e Pappaterra, non ci sentiamo appagati e lavoreremo tanto con il Governo quanto con la Regione per completare quella che consideriamo un\u2019opera strategica\u00bb, la conclusione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abAbbiamo inaugurato questa mattina il primo lotto funzionale della Scalea-Mormanno, un tratto di strada molto importante i cui lavori erano fermi da moltissimo tempo e che oggi daranno la possibilit\u00e0 non solo di poter fruire della normale viabilit\u00e0, ma anche di una maggiore transitabilit\u00e0 per finalit\u00e0 turistiche, proprio perch\u00e9 il collegamento \u00e8 fra l\u2019entroterra e [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":217175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-217174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=217174"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/217175"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=217174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=217174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=217174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}