{"id":217180,"date":"2023-11-20T18:52:47","date_gmt":"2023-11-20T17:52:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=217180"},"modified":"2024-11-11T16:55:04","modified_gmt":"2024-11-11T15:55:04","slug":"marano-principato-maltrattamenti-reiterati-ai-danni-dellex-compagna-divieto-di-avvicinamento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/marano-principato-maltrattamenti-reiterati-ai-danni-dellex-compagna-divieto-di-avvicinamento\/","title":{"rendered":"Marano Principato, maltrattamenti reiterati ai danni dell&#8217;ex compagna: divieto di avvicinamento"},"content":{"rendered":"<p>MARANO PRINCIPATO (CS) &#8211; Nel pomeriggio di oggi luned\u00ec 20 novembre, <strong>a Marano Principato<\/strong>, i <strong>carabinieri della sezione di Polizia Giudiziaria della Procura della Repubblica<\/strong> presso il Tribunale di Cosenza, hanno dato esecuzione all<strong>&#8216;ordinanza di applicazione della misura\/cautelare,<\/strong> ai danni di un cosentino incensurato, del <strong>divieto di avvicinamento all&#8217;ex compagna, <\/strong>vittima di <strong>reiterati maltrattamenti<\/strong> da parte dello stesso, ed emessa dal G.I.P. presso il Tribunale di Cosenza, su richiesta della Procura.<\/p>\n<p>I militari, nel corso delle investigazioni condotte in tempi brevissimi, hanno acquisito <strong>tutti gli elementi di responsabilit\u00e0 a carico dell&#8217;uomo<\/strong>, ricostruendo i <strong>comportamenti vessatori e violenti<\/strong> a carico della persona con cui intratteneva da anni una relazione sentimentale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARANO PRINCIPATO (CS) &#8211; Nel pomeriggio di oggi luned\u00ec 20 novembre, a Marano Principato, i carabinieri della sezione di Polizia Giudiziaria della Procura della Repubblica presso il Tribunale di Cosenza, hanno dato esecuzione all&#8216;ordinanza di applicazione della misura\/cautelare, ai danni di un cosentino incensurato, del divieto di avvicinamento all&#8217;ex compagna, vittima di reiterati maltrattamenti da [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":217181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-217180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=217180"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/217181"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=217180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=217180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=217180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}