{"id":21769,"date":"2013-05-03T20:00:00","date_gmt":"2013-05-03T18:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21769"},"modified":"2023-01-17T13:19:27","modified_gmt":"2023-01-17T12:19:27","slug":"8453-falsi-curriculum-condannata-finta-ostetrica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8453-falsi-curriculum-condannata-finta-ostetrica\/","title":{"rendered":"Falsi curriculum, condannata finta ostetrica"},"content":{"rendered":"<p>CATANZARO &#8211; Quando la disoccupazione aguzza l&#8217;ingegno.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Si e&#8217; concluso con una condanna ed un&#8217;assoluzione il processo a carico di due infermiere accusate di aver mentito a proposito di rispettive precedenti esperienze professionali in qualita&#8217; di ostetriche in modo da ottenere un maggior punteggio nella graduatoria finalizzata all&#8217;assunzione di &#8220;Collaboratore professionale sanitario-ostetrica&#8221;. Il giudice monocratico di Catanzaro, Barbara Fatale, ha <strong>assolto dalle accuse la 44enne Rita Arena &#8220;poiche&#8217; il fatto non sussiste&#8221;, come richiesto dall&#8217;avvocato Amedeo Bianco, condannando invece Cristina Salerno, 35enne di Ciro&#8217; Marina, a un anno e due mesi di reclusione,<\/strong> con concessione della sospensione condizionale della pena. Quest&#8217;ultima, secondo quanto contestato dal pubblico ministero, Paolo Petrolo, con &#8220;una dichiarazione sostitutiva presentata a febbraio del 2006 al Presidente straordinario dell&#8217;Azienda ospedaliera Pugliese-Ciaccio di Catanzaro&#8221; avrebbe dichiarato falsamente di &#8220;aver prestato servizio presso la struttura sanitaria di Villa Sant&#8217;Anna in qualita&#8217; di ostetrica, dal 01 settembre 2002 al 31 maggio 2004, mentre in realta&#8217; prestava servizio dal 21 ottobre 2002 al 6 maggio 2003 in qualita&#8217; di infermiera adibita al servizio in sala operatoria&#8221;. Cosi&#8217;, sempre secondo le accuse, avrebbe &#8220;indotto in errore con inganno la Commissione esaminatrice che, in forza delle false attestazioni, attribuiva alla Salerno, nella graduatoria finalizzata all&#8217;assunzione di collaboratore professionale sanitario-ostetrica cat. D presso l&#8217;Azienda ospedaliera Pugliese-Ciaccio il punteggio di 2,375 (collocandola al 4* posto)&#8221;. Una collocazione che secondo l&#8217;accusa non le sarebbe spettata e che arreco&#8217; dunque un danno ingiusto alle altre aspiranti al posto, una delle quali si e&#8217; costituita parte civile ottenendo un risarcimento di 2.500 euro oltre alla rifusione delle spese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Quando la disoccupazione aguzza l&#8217;ingegno.<\/p>\n","protected":false},"author":22,"featured_media":21770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-21769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21769"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21770"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}