{"id":21829,"date":"2013-05-06T07:13:44","date_gmt":"2013-05-06T05:13:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21829"},"modified":"2023-01-17T13:19:31","modified_gmt":"2023-01-17T12:19:31","slug":"8483-ndrangheta-il-denaro-si-ripulisce-con-la-frutta-ventidue-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8483-ndrangheta-il-denaro-si-ripulisce-con-la-frutta-ventidue-arresti\/","title":{"rendered":"&#8216;Ndrangheta, il denaro si &#8216;ripulisce&#8217; con la frutta. Ventidue arresti"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Soldi &#8216;sporchi&#8217; da Vibo a Viterbo, poi il rientro. La cosca Gallician\u00f2 sotto i riflettori delle forze dell&#8217;ordine.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Il Comando Provinciale di Reggio Calabria sta eseguendo un&#8217;Ordinanza di Custodia Cautelare, emessa dal G.I.P. presso il Tribunale di Reggio Calabria su richiesta della Direzione Distrettuale Antimafia, nei confronti di 22 persone ritenute appartenenti e contigue alla &#8216;ndrangheta nella sua articolazione territoriale chiamata &#8220;locale di Galliciano'&#8221; attiva a Condofuri in provincia di Reggio, nei territori limitrofi e nella provincia di Viterbo dove sono state scoperte ditte che &#8220;ripulivano&#8221; denaro sporco che poi &#8220;tornava&#8221; nel reggino. <strong>I 22 arrestati sono ritenuti responsabili a vario titolo, di associazione di tipo mafioso; detenzione illegale di armi comuni da sparo; concorso in riciclaggio; concorso in impiego di denaro, beni o utilita&#8217; di provenienza illecita.<\/strong> Durante le indagini partite nel settembre del 2009, i Carabinieri hanno accertato come nel comune di Condofuri siano operanti 3 locali di &#8216;ndrangheta: Condofuri Marina, San Carlo e Galliciano&#8217;. Le indagini hanno ulteriormente consentito di confermare e documentare le attivita&#8217; criminali e le sue dinamiche interne, anche attraverso l&#8217;assegnazione di cariche e gradi. Le investigazioni hanno inquadrato le attivita&#8217; della famiglia a capo della locale di Galliciano&#8217; ed hanno consentito di individuare <strong>un rodato sistema di riciclaggio di denaro che, partendo dalla Calabria, era ripulito attraverso le ditte nel Viterbese per tornare successivamente nel capoluogo reggino<\/strong>. Con il provvedimento restrittivo, \u00e8 stato eseguito un decreto di sequestro probatorio di 6 aziende, operanti nel settore dei trasporti, ortofrutticolo ed immobiliare. Il valore dei beni sequestrati dai Carabinieri di Reggio Calabria in alcune citta&#8217; del centro Italia, in particolare a Terni e Viterbo, nell&#8217;ambito dell&#8217;operazione, denominata &#8220;El Dorado&#8221;, ammonta a circa venti milioni di euro.&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Le persone arrestate nell&#8217;operazione coordinata dai Carabinieri di Reggio Calabria e condotta dalla locale Dda che ha scoperto l&#8217;esistenza di tre &#8220;locali&#8221; di &#8216;ndrangheta nel comune reggino di Condofuri. Si tratta di Antonino Casili, 58 anni; Alberto Corso, 37 anni; Augusto Corso, 51 anni; Domenico Foti, 55 anni; Concetto Manti, 43 anni; Tommaso Mesiano, 55 anni; Antonio Nucera, 72 anni; Antonio Nucera, 58 anni; Bruno Nucera, 55 anni; Carmelo Nucera, 63 anni; Carmelo Nucera, 43 anni; Diego Nucera, 65 anni; Domenico Nucera, 42 anni; Filippo Nucera, 72 anni; Francesco Nucera, 32 anni; Giuseppe Nucera, 67 anni; Raffaele Nucera, 50 anni; Raffaele Nucera, 40 anni; Roberto Raso, 41 anni; Pietro Roda&#8217;, 47 anni; Domenico Vitale, 54 anni; Girolamo Zindato, 40 anni. Le imprese sequestrate sono invece: T.C.I. Trasporti Centro Italia srl; Vitercalabra Autotrasporti srl; Nucera Trasporti srl; Ortofrutticola Cimina srl; Ortfruit Internazionale srl; Cimina Immobiliare srl.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Abbiamo dimostrato un&#8217;ingente attivita&#8217; di riciclaggio, attivita&#8217; economiche che hanno ricadute consistenti sul piano commerciale e imprenditoriale in altre realta&#8217; nazionali, e in particolare nel viterbese&#8221; ha affermato il comandante provinciale dell&#8217;Arma di Reggio Calabria, colonnello Lorenzo Falferi. &#8220;L&#8217;attivita&#8217; condotta dalla Compagnia di Melito Porto Salvo e dal Comando provinciale e coordinata dal procuratore aggiunto Nicola Gratteri &#8211; ha aggiunto Falferi &#8211; ha permesso di individuare nuovi locali di &#8216;ndrangheta, dimostrare le modalita&#8217; con cui venivano assegnate le cariche e le modalita&#8217; con cui avveniva il riciclaggio del denaro sporco. L&#8217;attivita&#8217; di sequestro &#8211; ha concluso il colonnello &#8211; nei confornti di attivita&#8217; commerciali, oltre a imprese di Viterbo, operanti nel campo immobiliare, di trasporto e ortofrutticolo, ha interssato anche un&#8217;impresa di Terni&#8221;. &#8220;Avevano creato un ponte nel viterbese dove avevano costiuito societa&#8217; per fare riciclaggio&#8221; ha detto, nel corso di una conferenza stampa, il procuratore aggiunto della DDA di Reggio Calabria, Nicola Gratteri. &#8220;Riciclavano i soldi di soggetti gia&#8217; conosciuti &#8211; ha aggiunto Gratteri &#8211; come ad esempio Rocco Musolino, che e&#8217; stato di recente interessato da un sequestro beni&#8221;. <strong>Secondo l&#8217;impianto accusatorio Rocco Musolino, noto imprenditore del settore boschivo operante a Santo Stefano d&#8217;Aspromonte, sarebbe entrato in contatto con Antonio Nucera, 58 anni, per il tramite di Domenico Vitale. Rocco Musolino non figura, tuttavia, tra i 22 soggetti destinatari di misura cautelare.<\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Soldi &#8216;sporchi&#8217; da Vibo a Viterbo, poi il rientro. La cosca Gallician\u00f2 sotto i riflettori delle forze dell&#8217;ordine.<\/p>\n","protected":false},"author":22,"featured_media":21830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-21829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21829"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21830"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}