{"id":218408,"date":"2023-12-12T06:30:42","date_gmt":"2023-12-12T05:30:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=218408"},"modified":"2023-12-12T07:22:09","modified_gmt":"2023-12-12T06:22:09","slug":"unical-troppe-barriere-architettoniche-e-nessuna-mappatura-presentata-nuova-interrogazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/unical-troppe-barriere-architettoniche-e-nessuna-mappatura-presentata-nuova-interrogazione\/","title":{"rendered":"Unical: troppe barriere architettoniche e nessuna mappatura, presentata nuova interrogazione"},"content":{"rendered":"<p>RENDE &#8211; Francesco <strong>Bossio<\/strong> in qualit\u00e0 di Senatore Accademico, unitamente a Riccardo <strong>Latella<\/strong>, in qualit\u00e0 di Consigliere di Amministrazione, gi\u00e0 lo scorso 24 ottobre avevano trasmesso al <strong>Senato Accademico un&#8217;interrogazione<\/strong> nella quale si chiedeva, tra l&#8217;altro, lo stato dell\u2019arte rispetto all\u2019abbattimento delle <strong>barriere architettoniche dell\u2019Universit\u00e0<\/strong> della Calabria. Una prima risposta in questione \u00e8 stata legata ad una mappatura che &#8220;risulta in itinere&#8221; in netta discordanza con quanto ufficialmente sancito dal <strong>PIAO (Piano Integrato delle Attivit\u00e0 e Organizzazione).\u00a0<\/strong><\/p>\n<p>La \u201cDelegata alle attivit\u00e0 concernenti l&#8217;integrazione degli Studenti con disabilit\u00e0 e con disturbi specifici di apprendimento nell&#8217;Ateneo\u201d nell\u2019ambito del corso TFA \u2013 Unical ha coordinato un convegno dal titolo \u201cAnalisi, riflessioni e testimonianze\u201d nel quale \u00e8 anche intervenuto uno <strong>studente con disabilit\u00e0<\/strong>, <strong>Silverio<\/strong>, il quale ha ricordato &#8220;l\u2019inefficacia e l\u2019inefficienza delle politiche gi\u00e0 attivate in materia di integrazione degli studenti con disabilit\u00e0 segnalate a suo tempo con l\u2019ausilio degli organi di stampa&#8221;. In un <strong>video Silverio<\/strong>, <strong>denunciava una situazione che ad oggi non ha trovato soluzione<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Silverio, studente Unical, denuncia: &quot;Funzionano 9 ascensori su 88: qui non vivo una vita libera&quot;\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/37vgabY2BQU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>In quella circostanza la delegata del rettore, durante il convegno ha dichiarato: \u201cAbbiamo avviato una ricognizione per comprendere la fattibilit\u00e0, perch\u00e9 questa \u00e8 una <strong>struttura che ha 50 anni<\/strong>, certi punti non possono essere resi accessibili per\u00f2 abbiamo fatto <strong>uno studio sulla fattibilit\u00e0<\/strong> di percorsi alternativi, in giro qualcosa \u00e8 stata fatta&#8221;.<\/p>\n<p>Per tali motivi Bossio e Latella chiedono una rettifica, con allegata motivazione dell\u2019errore trasmessa in forma scritta, su quanto attestato nelle risposte alle interrogazioni sulla mappatura dei percorsi di accessibilit\u00e0. Inoltre &#8220;dato per veritiero quanto affermato nel PIAO, richiedono la <strong>trasmissione integrale di tale mappatura<\/strong>, ai fini delle verifica di conformit\u00e0 alle normative in materia di barriere architettoniche&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-218633 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02.jpg\" alt=\"barriere architettoniche unical 02\" width=\"573\" height=\"355\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/barriere-architettoniche-unical-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 573px) 100vw, 573px\" \/><\/p>\n<p>E ancora richiedono una relazione da trasmettere in forma scritta al Senato Accademico e al Consiglio di Amministrazione, con valore di risposta all\u2019interrogazione inviata in data 24 ottobre al Senato Accademico, circa lo stato di conformit\u00e0 delle strutture dell&#8217;intero ateneo. Nello specifico, nonostante la normativa in questione non descriva come obbligatori interventi di adeguamento per strutture costruite antecedentemente alla sua emanazione, si richiede che nella relazione sia presente un <strong>confronto con le linee guida<\/strong> da essa stabilite prevedendo interventi dove lo stato dell\u2019arte delle strutture non fosse conforme a quanto prescritto. Infine la richiesta al rettore Leone ma anche alla Direzione Generale e alla delegata del rettore, di fornire una definizione di \u201c<strong>Ripristinato il percorso tattile<\/strong> <strong>esistente sul ponte carrabile\u201d<\/strong> considerato che, con il termine \u201cripristinato\u201d, si intende \u201cRimettere nello stato pristino, nelle condizioni di prima\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Francesco Bossio in qualit\u00e0 di Senatore Accademico, unitamente a Riccardo Latella, in qualit\u00e0 di Consigliere di Amministrazione, gi\u00e0 lo scorso 24 ottobre avevano trasmesso al Senato Accademico un&#8217;interrogazione nella quale si chiedeva, tra l&#8217;altro, lo stato dell\u2019arte rispetto all\u2019abbattimento delle barriere architettoniche dell\u2019Universit\u00e0 della Calabria. Una prima risposta in questione \u00e8 stata legata [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":218634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-218408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=218408"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/218634"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=218408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=218408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=218408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}