{"id":218742,"date":"2023-12-12T11:00:24","date_gmt":"2023-12-12T10:00:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=218742"},"modified":"2023-12-12T11:03:46","modified_gmt":"2023-12-12T10:03:46","slug":"m5s-ferrara-nominata-coordinatrice-del-comitato-per-i-rapporti-europei-e-internazionali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/m5s-ferrara-nominata-coordinatrice-del-comitato-per-i-rapporti-europei-e-internazionali\/","title":{"rendered":"M5S, Ferrara nominata coordinatrice del Comitato per i rapporti europei e internazionali"},"content":{"rendered":"<p>ROMA &#8211; &#8220;Ringrazio tutti gli attivisti del Movimento 5 Stelle che hanno confermato con il loro voto la proposta del Presidente Giuseppe Conte di nominarmi come coordinatrice del Comitato per i rapporti europei e internazionali&#8221;. Cos\u00ec in una nota <strong>Laura Ferrara<\/strong>, europarlamentare del Movimento 5 Stelle e <strong>neo coordinatrice del Comitato per i rapporti europei e internazionali.<\/strong><\/p>\n<p>Accetto questa sfida con grande umilt\u00e0 e spirito di servizio mettendomi a disposizione della comunit\u00e0 del Movimento 5 Stelle di cui faccio parte da 13 anni. Assieme agli altri membri del Comitato &#8211; Tiziana Beghin, Ettore Licheri , Bruno Marton e Filippo Scerra &#8211; che ringrazio fin da subito per la futura preziosa collaborazione, <strong>lavoreremo per rafforzare i presidi di pace che oggi mancano in Europa e dentro la comunit\u00e0 internazionale<\/strong>. In un mondo infiammato dalle due guerre in Ucraina e Medio Oriente, la nostra bussola sar\u00e0 lo Statuto dell&#8217;ONU, caposaldo per la sicurezza collettiva e il diritto internazionale.<\/p>\n<p>Come Movimento 5 Stelle consideriamo la pace non come un&#8217;utopia, ma come un complesso di azioni quotidiane che hanno l&#8217;ambizione di cambiare in meglio la nostra societ\u00e0. Il prossimo appuntamento elettorale delle elezioni europee sar\u00e0 decisivo per il futuro delle prossime generazioni e noi lo affronteremo <strong>collaborando con tutte le forze progressiste e ambientaliste<\/strong> per respingere i tentativi di chi vorrebbe riportare le lancette dell&#8217;orologio all&#8217;epoca della Societ\u00e0 delle Nazioni. Per il bene delle nostre imprese e di tutti i cittadini l&#8217;orizzonte dell&#8217;Italia non pu\u00f2 che essere quello europeo&#8221;,.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; &#8220;Ringrazio tutti gli attivisti del Movimento 5 Stelle che hanno confermato con il loro voto la proposta del Presidente Giuseppe Conte di nominarmi come coordinatrice del Comitato per i rapporti europei e internazionali&#8221;. Cos\u00ec in una nota Laura Ferrara, europarlamentare del Movimento 5 Stelle e neo coordinatrice del Comitato per i rapporti europei [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":190494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-218742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=218742"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/190494"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=218742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=218742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=218742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}