{"id":218790,"date":"2023-12-12T14:50:49","date_gmt":"2023-12-12T13:50:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=218790"},"modified":"2023-12-12T14:43:00","modified_gmt":"2023-12-12T13:43:00","slug":"ancora-violenze-e-maltrattamenti-in-famiglia-due-arresti-a-campana-e-corigliano-rossano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ancora-violenze-e-maltrattamenti-in-famiglia-due-arresti-a-campana-e-corigliano-rossano\/","title":{"rendered":"Ancora casi di violenze e maltrattamenti in famiglia. Due arresti a Campana e Corigliano Rossano"},"content":{"rendered":"<p>COSENZA &#8211; Nella giornata di ieri sono stati <strong>arrestati due uomini per due distinte vicende<\/strong>, che hanno in comune<strong> le donne quali vittime e le mura domestiche come teatro dei reati contestati<\/strong>. Un settore dove i Carabinieri del Reparto Territoriale di Corigliano Rossano, con il coordinamento della Procura della Repubblica di Castrovillari, diretta dal Procuratore Alessandro D\u2019Alessio, pongono la massima attenzione, anche alla luce delle innovazioni legislative emanate di recente.<\/p>\n<h3>Aggressione alla compagna nella frazione Cantinella<\/h3>\n<p>La vicenda, alla quale \u00e8 poi conseguito l\u2019arresto di un <strong>soggetto gi\u00e0 noto alle Forze dell\u2019Ordine<\/strong>, \u00e8 iniziata nel pomeriggio di ieri, quando con una serie di chiamate al \u00ab112\u00bb, effettuate da <strong>cittadini terrorizzati per il trambusto che arrivava da un appartamento della frazione Cantinella di Corigliano Rossano<\/strong>, \u00e8 stata segnalata una potenziale aggressione. Sul posto, valutato il rischio per la vittima, sono state fatte subito arrivare diverse pattuglie dell\u2019Arma, appartenenti alla Stazione di Corigliano Scalo, alla Radiomobile del Reparto Territoriale ed alle S.I.O del 14\u00b0 Battaglione Calabria.<\/p>\n<h3>Accusato anche di tentata estorsione<\/h3>\n<p>Sul posto i militari hanno potuto constatare quello che era effettivamente accaduto e raccogliere una serie di elementi indiziari in relazione alle responsabilit\u00e0 dell\u2019uomo, in ordine alla <strong>reiterazione dei maltrattamenti in famiglia<\/strong> <strong>posti in essere nei confronti della compagna<\/strong>, delle lesioni cagionate alla stessa ed a un suo congiunto e di una <strong>tentata estorsione in ordine all\u2019iniziativa dell\u2019indagato.<\/strong> Quest\u2019ultima ipotesi di reato riferibile alla pretesa antigiuridica del soggetto attivo di alcune somme di danaro appena ricevute dalla parte lesa. L\u2019arrestato, al termine delle incombenze di legge \u00e8 stato associato presso il Carcere di Castrovillari, dove rimarr\u00e0 a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<h3>Campana, 4 anni di carcere per reiterazione del reato<\/h3>\n<p>Analoga sorte \u00e8 toccata ad<strong> un altro uomo residente a Campana, che per i maltrattamenti in famiglia<\/strong> effettuati negli anni scorsi era gi\u00e0 stato ristretto in regime di detenzione domiciliare. La rideterminazione della pena, conseguita per la r<strong>eiterazione del reato<\/strong>, ha determinato <strong>una condanna complessiva a carico dell\u2019interessato di oltre 4 anni di carcere,<\/strong> ragione per la quale lo stesso \u00e8 stato arrestato e tradotto, anche lui, presso il carcere di Castrovillari.<\/p>\n<p>Le misure adottate, anche se di natura giuridica diversa, dimostrano come continui a permanere alta l\u2019attenzione del Carabinieri del Reparto Territoriale e della Procura di Castrovillari nel contrasto a quella che possiamo tranquillamente definire la piaga sociale delle violenze domestiche poste in essere nei confronti delle persone pi\u00f9 vulnerabili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nella giornata di ieri sono stati arrestati due uomini per due distinte vicende, che hanno in comune le donne quali vittime e le mura domestiche come teatro dei reati contestati. Un settore dove i Carabinieri del Reparto Territoriale di Corigliano Rossano, con il coordinamento della Procura della Repubblica di Castrovillari, diretta dal Procuratore [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":218791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-218790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=218790"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/218791"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=218790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=218790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=218790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}