{"id":219213,"date":"2023-12-19T14:04:00","date_gmt":"2023-12-19T13:04:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=219213"},"modified":"2023-12-19T14:04:22","modified_gmt":"2023-12-19T13:04:22","slug":"arrestato-lautore-di-5-rapine-tra-cosenza-e-rende-adescava-le-vittime-anche-online","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/arrestato-lautore-di-5-rapine-tra-cosenza-e-rende-adescava-le-vittime-anche-online\/","title":{"rendered":"Arrestato l&#8217;autore di 5 rapine tra Cosenza e Rende: adescava le vittime anche online"},"content":{"rendered":"<p>COSENZA &#8211; Nel pomeriggio di ieri, la Polizia di Stato, ha<strong> arrestato un giovane straniero,<\/strong> <strong>domiciliato a Cosenza pregiudicato per reati specifici,<\/strong> sottoponendolo alla misura degli arresti domiciliari, in quanto resosi responsabile di una serie di rapine, commesse negli scorsi mesi. Il provvedimento \u00e8 l\u2019epilogo di una intensa attivit\u00e0 d\u2019indagine, coordinata dalla Procura della Repubblica di Cosenza, diretta dal Procuratore Mario Spagnuolo, ed avviata a seguito dei diversi episodi predatori registratisi.<\/p>\n<p>In particolare, l\u2019indagato, lo scorso settembre, era stato arrestato in flagranza in relazione alla <strong>rapina perpetrata a Cosenza ai danni di una anziana donna<\/strong>, che nell\u2019occasione \u00e8 stata strattonata fino a cadere rovinosamente a terra, riportando ferite giudicate guaribili in 30 giorni.<\/p>\n<p>Le indagini successive, supportate da denunce e dichiarazioni delle vittime, nonch\u00e9 l\u2019analisi delle telecamere dei sistema di videosorveglianza pubblico e privato (attraverso cui gli operatori hanno in diverse circostanze riconosciuto l&#8217;uomo come autore dei reati contestati<em>)<\/em>, hanno premesso di<strong> attribuire all\u2019uomo la responsabilit\u00e0 di 5 episodi di rapina perpetrati nel capoluogo bruzio ed a Rende<\/strong> nel periodo compreso <strong>tra il mese di luglio ed il mese di settembre 2023<\/strong>. All\u2019indagato,\u00a0 inoltre, sono stati contestati i reati di lesioni aggravate procurate a diverse delle vittime, nonch\u00e9 il porto ingiustificato di oggetti atti ad offendere.<\/p>\n<p>Il lavoro certosino e scrupoloso degli investigatori, che non hanno trascurato alcun dettaglio, ha consentito di ricondurre gli eventi presi in esame, ad un\u2019unica matrice criminale, valutato anche il modus operandi dei malfattori. Determinante \u00e8 stato anche il contributo degli operatori della Polizia Scientifica.<\/p>\n<p>Dall\u2019indagine \u00e8 emerso che <strong>l\u2019arrestato, non solo commetteva rapine a vittime scelte casualmente, incrociate per strada, ma che in diversi casi, tramite siti on line, adescava uomini, che poi incontrava con il pretesto di iniziare amicizia od intraprendere una relazione, salvo poi rapinarli al momento dell\u2019incontro<\/strong>, <strong>facendosi consegnare denaro, smartphone e persino delle autovetture.<\/strong> Una delle rapine \u00e8 stata perpetrata ai danni una parafarmacia.<\/p>\n<p>Espletate le formalit\u00e0 di rito, l\u2019uomo \u00e8 stato condotto in carcere a Cosenza. Il giovane straniero poche settimane fa era stato nuovamente arrestato in flagranza di reato per i delitti di evasione e rapina, commessa in questo centro, ai danni di un giovane.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nel pomeriggio di ieri, la Polizia di Stato, ha arrestato un giovane straniero, domiciliato a Cosenza pregiudicato per reati specifici, sottoponendolo alla misura degli arresti domiciliari, in quanto resosi responsabile di una serie di rapine, commesse negli scorsi mesi. Il provvedimento \u00e8 l\u2019epilogo di una intensa attivit\u00e0 d\u2019indagine, coordinata dalla Procura della Repubblica [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":195894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-219213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/219213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=219213"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/219213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/195894"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=219213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=219213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=219213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}