{"id":219214,"date":"2023-12-19T14:40:12","date_gmt":"2023-12-19T13:40:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=219214"},"modified":"2023-12-19T14:35:39","modified_gmt":"2023-12-19T13:35:39","slug":"manna-comune-sciolto-da-6-mesi-e-ancora-non-conosciamo-le-ragioni-la-politica-si-e-dileguata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/manna-comune-sciolto-da-6-mesi-e-ancora-non-conosciamo-le-ragioni-la-politica-si-e-dileguata\/","title":{"rendered":"Manna: \u00abComune sciolto da 6 mesi e ancora non conosciamo le ragioni. La politica si \u00e8 dileguata\u00bb"},"content":{"rendered":"<p>RENDE &#8211; Conferenza stampa per il<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/bufera-giudiziaria-su-manna-inchieste-anomale-e-poteri-forti-contro-di-me-ve-lo-dimostro\" target=\"_blank\" rel=\"noopener\"> sindaco<\/a> sospeso di Rende<strong> Marcello Manna<\/strong> che ha parlato ai giornalisti sia della situazione <strong>relativa allo scioglimento del Comune di Rende<\/strong> ma anche della situazione giudiziaria che lo riguarda e definita da Manna <strong>&#8220;il grande imbroglio<\/strong>&#8220;. \u00abSono trascorsi sei mesi da quando \u00e8 stato sciolto il Consiglio comunale di Rende e <strong>ancora non conosciamo le ragioni di questo provvedimento<\/strong>, anche perch\u00e9, ancora, non abbiamo<strong> avuto la possibilit\u00e0 di visionare la relazione della Commissione d\u2019Accesso<\/strong>, nonostante una formale richiesta effettuata alla Prefettura di Cosenza (ricorso al Tar) e sebbene la Procura della Repubblica ha confermato che non sia pi\u00f9 secretata\u00bb- ha spiegato l\u2019ex sindaco di Rende sul commissariamento del comune d\u2019Oltre Campagnano.<\/p>\n<p>\u00ab<strong>Si tratta di sentire le ragioni e capire cosa \u00e8 accaduto a Rende<\/strong> dal punto di vista giudiziario, dei provvedimenti emessi dal Ministero degli Interni e dalla politica\u00bb. L&#8217;ex sindaco di Rende sottolinea anche come<strong> la politica, quando c\u2019\u00e8 un provvedimento di scioglimento si dilegua, com\u2019\u00e8 accaduto per esempio per i Comuni di Cir\u00f2, Strongoli, Caccuri,<\/strong> sciolti per mafia tre anni fa e la sentenza uscita nelle scorse settimane che <strong>ha riabilitato gli amministratori perch\u00e9 assolti per non aver commesso il fatto<\/strong>.<\/p>\n<p>Poi c\u2019\u00e8 un altro aspetto, quello che Manna definisce un<strong>\u00a0\u201cgrande imbroglio\u201d,<\/strong> almeno da quello che emerge dagli atti in suo possesso, a partire da quelli giudiziari che sono stati quasi tutti revocati: \u00ab<strong>noi abbiamo solo da rivendicare il buon governo della citt\u00e0 di Rende<\/strong> che \u00e8 uscito dal pre-dissesto. Questo diciamolo, perch\u00e9 i comuni posso essere sciolti a causa di una cattiva gestione, ma in questo caso vorremmo capire quale sia la cattiva gestione\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Conferenza stampa per il sindaco sospeso di Rende Marcello Manna che ha parlato ai giornalisti sia della situazione relativa allo scioglimento del Comune di Rende ma anche della situazione giudiziaria che lo riguarda e definita da Manna &#8220;il grande imbroglio&#8220;. \u00abSono trascorsi sei mesi da quando \u00e8 stato sciolto il Consiglio comunale di [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":219216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[19,135],"class_list":["post-219214","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","category-rende","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/219214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=219214"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/219214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/219216"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=219214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=219214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=219214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}