{"id":21930,"date":"2013-05-08T05:40:44","date_gmt":"2013-05-08T03:40:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=21930"},"modified":"2023-01-17T13:19:36","modified_gmt":"2023-01-17T12:19:36","slug":"8535-la-provincia-italiana-che-paga-di-piu-e-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8535-la-provincia-italiana-che-paga-di-piu-e-cosenza\/","title":{"rendered":"La Provincia italiana che paga di pi\u00f9? E&#8217; Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; La Provincia bruzia sul podio per il pagamento dei debiti ad imprese e fornitori.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Quella di Cosenza e&#8217; tra le prime tre Province d&#8217;Italia, insieme alle Province di Milano e Varese ed e&#8217; la prima in Calabria e nel Mezzogiorno per debiti pagati alle imprese per forniture, lavori pubblici e altri debiti in conto capitale. E quanto si si leggei sull&#8217;autorevole quotidiano economico nazionale &#8220;Il Sole 24 Ore&#8221; in un articolo a firma di Eugenio Bruno e Carmine Fotina intitolato &#8220;Debiti Pa, i tempi si allungano&#8221;. Per nulla sorpreso il presidente Oliverio che, nei mesi scorsi, illustrando la virtuosita&#8217; dei conti dell&#8217;ente, ha piu&#8217; volte sostenuto<strong> la celerita&#8217; con cui la Provincia di Cosenza ha sempre liquidato in tempi brevi quanto dovuto alle imprese, evitando attese che, per molte di esse, avrebbero potuto comportare sofferenze pesanti e, in alcuni casi, anche il loro fallimento.<\/strong> La notizia apparsa sul &#8220;Sole 24 ore&#8221; di oggi dice, infatti, che il rapporto tra le imprese e la Provincia di Cosenza, nonostante la grave crisi finanziaria ed economica che investe il Paese ed i tagli governativi subiti nell&#8217;ultimo biennio 2011-2012 che ammontano a oltre 34 milioni di euro, e&#8217; in netta controtendenza rispetto alla media nazionale dei tempi di pagamento di tantissime Pubbliche amministrazioni. Ricordiamo a tal proposito che, proprio a seguito di tale situazione, e&#8217; stato emanato il Decreto Legge 35, denominato anche &#8220;decreto sbloccadebiti&#8221;, che prevede una dotazione complessiva di quaranta miliardi alla Pubblica Amministrazione per il biennio 2013-2014, nato proprio con l&#8217;intento di immettere liquidita&#8217; alle casse degli enti per metterle in condizione di eseguire nel minor tempo possibile i pagamenti contratti nel tempo con le imprese. &#8220;Questa ulteriore performance positiva, che pone la Provincia tra gli enti piu&#8217; virtuosi d&#8217;Italia -ha affermato il presidente Oliverio, commentando la notizia- ci gratifica e ci spinge a proseguire sulla strada imboccata. A tal proposito voglio ringraziare il Direttore Generale dell&#8217;ente Antonio Molinari, i settori e gli uffici per avere reso possibile, con il loro lavoro, anche questo straordinario risultato&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La Provincia bruzia sul podio per il pagamento dei debiti ad imprese e fornitori.<\/p>\n","protected":false},"author":22,"featured_media":21931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-21930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=21930"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/21930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/21931"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=21930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=21930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=21930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}