{"id":219861,"date":"2024-01-01T08:30:45","date_gmt":"2024-01-01T07:30:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=219861"},"modified":"2024-01-01T08:15:20","modified_gmt":"2024-01-01T07:15:20","slug":"capodanno-703-interventi-dei-vigili-del-fuoco-tre-donne-ferite-da-proiettili-in-campania-una-e-grave","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/capodanno-703-interventi-dei-vigili-del-fuoco-tre-donne-ferite-da-proiettili-in-campania-una-e-grave\/","title":{"rendered":"Capodanno, 703 interventi dei vigili del fuoco. Tre donne ferite da proiettili in Campania, una \u00e8 grave"},"content":{"rendered":"<p>COSENZA &#8211; Sono stati <strong>703 stanotte gli interventi dei vigili del fuoco per incendi riconducibili ai festeggiamenti di Capodanno<\/strong>, in leggero aumento rispetto allo scorso anno, quando furono 646. Molti interventi hanno riguardato <strong>incendi di cassonetti, alcune autovetture parcheggiate in strada<\/strong>. Il numero maggiore in Emilia Romagna, dove sono stati 101. Gli altri interventi sono stati in Piemonte 46, Lombardia 69, Veneto e Trentino Alto Adige 47, Friuli Venezia Giulia 21, Liguria 42, Toscana 49, Marche 25, Umbria 22, Lazio 74, Abruzzo 16, Molise 1, Campania 38, Basilicata 6, <strong>Calabria 9<\/strong>, Puglia 60, Sicilia 52, Sardegna 25.<\/p>\n<p>Per quanto riguarda i feriti tre donne sono state colpite a Napoli da proiettili vaganti.\u00a0Nel quartiere Forcella, mentre assisteva dal balcone di casa ai fuochi d&#8217;artificio per il nuovo anno, una donna sarebbe stata c<strong>olpita all&#8217;addome da un proiettile vagante<\/strong>. \u00c8 accaduto nel quartiere di Forcella. La donna \u00e8 stata trasportata all&#8217;ospedale Vecchio Pellegrini ma mon sarebbe in pericolo di vita. L&#8217;incidente segue di alcune ore quello che ha coinvolto un<strong> bambino di 11 anni ad Alfano, in provincia di Salern<\/strong>o. Il piccolo <strong>stava maneggiando un petardo, che gli \u00e8 esploso in faccia<\/strong>. Immediati i soccorsi e la corsa all&#8217;ospedale: i medici gli hanno riscontrato un grave trauma all&#8217;occhio, la cui funzionalit\u00e0 sarebbe stata definitivamente compromessa. Sempre a Napoli una 50enne si \u00e8 recata al pronto Soccorso con una <strong>ferita da colpi di pistola al fianco<\/strong>.<\/p>\n<p>Stessa sorte anche per una donna di 45 anni di\u00a0<strong>Afragola<\/strong>, f<strong>erita da un proiettile vagante durante i festeggiamenti per il capodanno<\/strong>. Secondo una prima ricostruzione dei carabinieri la vittima sarebbe stata colpita mentre festeggiava con i parenti all\u2019interno di un\u2019abitazione. La signora \u00e8 in gravi condizioni e in pericolo di vita.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sono stati 703 stanotte gli interventi dei vigili del fuoco per incendi riconducibili ai festeggiamenti di Capodanno, in leggero aumento rispetto allo scorso anno, quando furono 646. Molti interventi hanno riguardato incendi di cassonetti, alcune autovetture parcheggiate in strada. Il numero maggiore in Emilia Romagna, dove sono stati 101. Gli altri interventi sono [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":219862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-219861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/219861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=219861"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/219861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/219862"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=219861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=219861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=219861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}