{"id":220093,"date":"2024-01-04T13:01:05","date_gmt":"2024-01-04T12:01:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=220093"},"modified":"2024-01-04T13:01:05","modified_gmt":"2024-01-04T12:01:05","slug":"cosenza-i-percorsi-tattili-per-ciechi-su-corso-mazzini-sono-nel-degrado","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-i-percorsi-tattili-per-ciechi-su-corso-mazzini-sono-nel-degrado\/","title":{"rendered":"Cosenza, i percorsi tattili per ciechi su Corso Mazzini sono nel degrado"},"content":{"rendered":"<p class=\"v1x_MsoNormal\">COSENZA &#8211; Oggi, \u00e8 la giornata mondiale del braille, sistema di lettura e scrittura per ciechi e ipovedenti<b>,<\/b> un sistema e una soluzione che ha permesso a queste persone di mettersi al fianco di chi non ha alcuna disabilit\u00e0 visiva e poter accedere, quanto pi\u00f9 possibile, agli stessi strumenti e agli stessi servizi. In tale occasione \u2013 sottolinea <strong>Pietro Molinaro Consigliere Regionale della Lega<\/strong> \u2013 segnalo che buona parte percorsi tattili, a servizio dei ciechi e ipovedenti,\u00a0\u00a0installati su corso Mazzini, quello che viene indicato come il salotto della citt\u00e0 di Cosenza, sono divelti , frastagliati oppure completamente danneggiati e quindi di fatto inservibili.<\/p>\n<p class=\"v1x_MsoNormal\">I pannelli si trovano abbandonati finanche in alcune traverse. <strong>I percorsi che via via si sono deteriorati, sono stati, sin qui, solo parzialmente rimessi a posto<\/strong>. E&#8217; un vero peccato\u00a0\u00a0&#8211; evidenzia Molinaro &#8211; perch\u00e9 \u00e8 un&#8217;installazione\u00a0\u00a0utile per le persone gi\u00e0 gravemente provate dalla vita che frequentano il corso principale di un citt\u00e0 da sempre vocata al sociale. Questi sentieri, che si snodano lungo il corso,\u00a0\u00a0sono estremamente utili- continua \u2013 e servono a facilitare la passeggiata delle persone cieche\u00a0\u00a0lungo il corso principale del capoluogo fermandosi addirittura davanti alle statue del Mab.<\/p>\n<p class=\"v1x_MsoNormal\">Cosenza ha nelle sue corde la possibilit\u00e0 di diventare la citt\u00e0 pi\u00f9 accessibile d&#8217;Italia per le persone non vedenti. Oggi, con rammarico,\u00a0\u00a0sia personalmente che attraverso\u00a0\u00a0una serie di segnalazioni\u00a0\u00a0&#8211; conclude\u00a0\u00a0&#8211; constato\u00a0\u00a0<strong>che con il passare del tempo, c&#8217;\u00e8 incuria e trascuratezza.<\/strong> Anche le <strong>panchine in marmo risultano danneggiate e sicuramente non fanno una buona impressione.<\/strong> Sono certo che l&#8217;Amministrazione Comunale interverr\u00e0 con sollecitudine per ripristinare i percorsi tattili per\u00a0\u00a0le persone con disabilit\u00e0 visiva e le panchine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Oggi, \u00e8 la giornata mondiale del braille, sistema di lettura e scrittura per ciechi e ipovedenti, un sistema e una soluzione che ha permesso a queste persone di mettersi al fianco di chi non ha alcuna disabilit\u00e0 visiva e poter accedere, quanto pi\u00f9 possibile, agli stessi strumenti e agli stessi servizi. In tale [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":220095,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-220093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=220093"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/220095"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=220093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=220093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=220093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}