{"id":22031,"date":"2013-05-09T08:17:45","date_gmt":"2013-05-09T06:17:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22031"},"modified":"2023-01-17T13:19:42","modified_gmt":"2023-01-17T12:19:42","slug":"8587-lite-tra-madre-e-figlio-intervengono-i-carabinieri-lui-li-aggredisce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8587-lite-tra-madre-e-figlio-intervengono-i-carabinieri-lui-li-aggredisce\/","title":{"rendered":"Lite tra madre e figlio, intervengono i carabinieri lui li aggredisce"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vibo Valentia &#8211; Violenza in famiglia e resistenza a pubblico ufficiale. Queste le accuse per le quali e&#8217; stato posto in stato di fermo da parte dei carabinieri, G. M., 30 anni, di Stefanaconi, in provincia di Vibo Valentia. <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I carabinieri guidati dal maresciallo Ciro Russo, comandante del Nucleo Radiomobile della Compagnia, sono intervenuti per sedare una lite fra l&#8217;uomo e la propria madre scoppiata nel&#8217;abitazione dei due. Alla vista dei militari dell&#8217;Arma, l&#8217;uomo ha reagito aggredendoli e spintonandoli. Di qui il fermo in attesa della convalida dell&#8217;arresto da parte del magistrato.<\/span><strong><br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vibo Valentia &#8211; Violenza in famiglia e resistenza a pubblico ufficiale. Queste le accuse per le quali e&#8217; stato posto in stato di fermo da parte dei carabinieri, G. M., 30 anni, di Stefanaconi, in provincia di Vibo Valentia.<\/p>\n","protected":false},"author":22,"featured_media":22032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-22031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22031"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22032"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}