{"id":220418,"date":"2024-01-09T17:33:08","date_gmt":"2024-01-09T16:33:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=220418"},"modified":"2024-01-09T18:20:35","modified_gmt":"2024-01-09T17:20:35","slug":"caso-bergamini-in-aula-le-autopsie-discrepanti-morto-per-emorrogia-o-soffocamento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/caso-bergamini-in-aula-le-autopsie-discrepanti-morto-per-emorrogia-o-soffocamento\/","title":{"rendered":"Caso Bergamini, in aula le autopsie discrepanti: morto per emorragia o soffocamento?"},"content":{"rendered":"<p>COSENZA &#8211; Nuova udienza, decisamente attesa, quella celebrata in Corte d&#8217;Assise a Cosenza nell\u2019ambito del processo seguito alla <strong>morte di Donato Bergamini<\/strong>, avvenuta a Roseto Capo Spulico nel novembre del 1989. Unica imputata, lo ricordiamo, \u00e8 l&#8217;ex fidanzata Isabella Intern\u00f2.<\/p>\n<p>Nell&#8217;udienza odierna \u00e8 stato sentito il <strong>professor Francesco Maria Avato<\/strong>, <strong>ovvero colui il quale aveva eseguito l\u2019autopsia nel gennaio del 1990. <\/strong>Avato ha sottolineato alcuni particolari legati al suo lavoro, ovvero gli scarsi elementi in suo possesso all&#8217;epoca: <strong>non gli sarebbe stato fornito il verbale redatto dalle forze dell\u2019ordine, n\u00e9 alcun dettaglio sugli indumenti, n\u00e8 c\u2019\u00e8 stato alcun confronto con la magistratura. <\/strong>Nel corso dell&#8217;udienza sono emerse discrepanze rispetto ai risultati dell\u2019autopsia eseguita successivamente, ovvero nel 2017, legate anche alle diverse strumentazioni e alle tecnologie utilizzate, che in circa 30 anni, come \u00e8 ovvio che sia, sono cambiate. Avato, inoltre, ha sottolineato i suoi dubbi sull\u2019ormai famosa glicoforina ed ha dichiarato che non ci sarebbe prova del soffocamento non avendo riscontrato, nell&#8217;autopsia del 1990, segni sul collo del calciatore. Lo stesso Avato ha sottolineato poi <strong>altri aspetti particolari<\/strong>: dalle sue risultanze, infatti, il corpo sarebbe stato disteso al suolo nel momento in cui sarebbe stato sormontato dal camion. Da alcune foto, poi, secondo Avato, sembra che il corpo del giocatore sia stato a contatto con il terreno senza vestiti.<\/p>\n<p>Diverse, quindi, le<strong> discrepanze fra i risultati delle due autopsie effettuate a 27 anni di distanza<\/strong>; in particolare <strong>diverse le conclusioni sul presunto soffocamento<\/strong>. Motivo per cui il Pm Primicerio ha chiesto un confronto fra il professore Avato e chi ha effettuato poi la successiva autopsia nel 2017 con i rispettivi periti gi\u00e0 sentiti nel corso del processo, presenti in aula. La richiesta \u00e8 stata accolta dalla Corte. Dal confronto, tuttavia, non sono emerse particolari novit\u00e0: <strong>Avato ha confermato di non individuare nell&#8217;asfissia la causa della morte, dovuta, invece all\u2019emorragia seguita al sormontamento<\/strong>. <strong>Gli esperti che hanno eseguito l\u2019autopsia nel 2017,<\/strong> con altri strumenti, ritengono la morte dovuta ad asfissia meccanica attraverso uno strumento soft, <strong>ovvero la tesi del soffocamento<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nuova udienza, decisamente attesa, quella celebrata in Corte d&#8217;Assise a Cosenza nell\u2019ambito del processo seguito alla morte di Donato Bergamini, avvenuta a Roseto Capo Spulico nel novembre del 1989. Unica imputata, lo ricordiamo, \u00e8 l&#8217;ex fidanzata Isabella Intern\u00f2. Nell&#8217;udienza odierna \u00e8 stato sentito il professor Francesco Maria Avato, ovvero colui il quale aveva [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":189595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19,135],"class_list":["post-220418","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=220418"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/189595"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=220418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=220418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=220418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}