{"id":220672,"date":"2024-01-12T19:35:00","date_gmt":"2024-01-12T18:35:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=220672"},"modified":"2024-01-12T19:35:00","modified_gmt":"2024-01-12T18:35:00","slug":"due-arrivi-e-tre-partenze-mercato-nel-vivo-in-casa-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/due-arrivi-e-tre-partenze-mercato-nel-vivo-in-casa-cosenza\/","title":{"rendered":"Due arrivi e tre partenze: mercato nel vivo in casa Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; Porte girevoli in casa <strong>Cosenza<\/strong>, ma, in questo periodo dell&#8217;anno, \u00e8 un qualcosa di abbastanza frequente. Il <strong>mercato di gennaio<\/strong> scalda l&#8217;atmosfera, ma le squadre, intanto, <strong>devono pensare ai prossimi impegni di campo<\/strong> perch\u00e9 \u00e8 arrivato il girone di ritorno.<\/p>\n<p>Avvio decisamente difficile per la squadra di <strong>Caserta<\/strong>, che giocher\u00e0 a <strong>Cremona<\/strong> e che al di l\u00e0 delle voci circolate dopo la sconfitta casalinga contro il Como, \u00e8 ancora al timone di una squadra che, per\u00f2, <strong>nelle ultime dieci giornate ha ottenuto solo 7 punti<\/strong> e necessita di un cambio di marcia immediato.<\/p>\n<p>Per farlo <strong>il tecnico di Melito Porto Salvo avr\u00e0 ora a disposizione altri due uomini<\/strong>. Nelle ultime ore, infatti, sono arrivati due rinforzi: il primo \u00e8 <strong>Michele Camporese<\/strong>, difensore centrale, che ha gi\u00e0 giocato a Cosenza nella stagione 21\/22 arrivando sempre a gennaio e portando a casa <strong>15 presenze realizzando anche 5 gol<\/strong>. Il secondo \u00e8 <strong>Gianluca Frabotta<\/strong>, esterno sinistro di difesa, proveniente dal <strong>Bari<\/strong>, ma noto soprattutto per aver disputato <strong>una stagione con la Juventus di Pirlo con 15 presenze in serie A<\/strong>.<\/p>\n<p>Porte girevoli, per\u00f2, perch\u00e9 in tre sono stati ceduti al <strong>Monopoli<\/strong>: si tratta di <strong>Alessandro Arioli<\/strong>, buon protagonista delle prime gare di quest&#8217;anno, <strong>Dario La Vardera e Marin Cubretovic<\/strong>. I primi due in prestito, Cubretovic a titolo definitivo.<\/p>\n<p>Saranno sufficienti questi acquisti per riuscire a permettere al Cosenza di rimettersi in carreggiata? Lo vedremo, ma<strong> il mercato non si ferma qu\u00ec<\/strong> ed in uscita potrebbe esserci <strong>Viviani<\/strong>, in entrata un centrocampista con il vizio del gol. Fino all&#8217;ultimo minuto, per\u00f2, nel mercato, lo sappiamo, tutto \u00e8 possibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Porte girevoli in casa Cosenza, ma, in questo periodo dell&#8217;anno, \u00e8 un qualcosa di abbastanza frequente. Il mercato di gennaio scalda l&#8217;atmosfera, ma le squadre, intanto, devono pensare ai prossimi impegni di campo perch\u00e9 \u00e8 arrivato il girone di ritorno. Avvio decisamente difficile per la squadra di Caserta, che giocher\u00e0 a Cremona e [&hellip;]<\/p>\n","protected":false},"author":65,"featured_media":209645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19,135],"class_list":["post-220672","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-sport","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=220672"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/209645"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=220672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=220672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=220672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}