{"id":220877,"date":"2024-01-22T06:30:41","date_gmt":"2024-01-22T05:30:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=220877"},"modified":"2024-01-20T12:58:38","modified_gmt":"2024-01-20T11:58:38","slug":"ll-test-genetico-puo-indicare-la-terapia-piu-efficace-per-le-donne-con-tumore-al-seno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ll-test-genetico-puo-indicare-la-terapia-piu-efficace-per-le-donne-con-tumore-al-seno\/","title":{"rendered":"ll test genetico pu\u00f2 indicare la terapia pi\u00f9 efficace per le donne con tumore al seno"},"content":{"rendered":"<p>ROMA &#8211; \u00c8 uno dei temi pi\u00f9 importanti della medicina oggi: scoprire la presenza di un difetto genetico specifico (l&#8217;alterazione dei geni BRCA1 e BRCA2 ) pu\u00f2 indicare\u00a0\u00a0la terapia pi\u00f9 efficace per le donne colpite da tumore del seno. Per questo sulla prestigiosa rivista <strong>Journal of Clinical Oncology<\/strong>\u00a0pochi giorni fa sono stati pubblicate, dopo revisione sistematica della letteratura scientifica, le raccomandazionii della <strong>societ\u00e0 scientifica ASCO<\/strong> insieme all&#8217;<strong>Associazione dei Chirurghi Senologi Americani.<\/strong><\/p>\n<h3><strong>Test anticancro: a chi proporlo?<\/strong><\/h3>\n<p>&#8220;Dalla lettura dello studio emergono importanti\u00a0\u00a0novit\u00e0 sull&#8217;utilizzo dei test genetici &#8211;\u00a0\u00a0spiega\u00a0<strong>la Prof.ssa Emanuela Lucci Cordisco, genetista medico e ricercatore dell&#8217;Universit\u00e0 Cattolica di Roma e dirigente Medico\u00a0\u00a0presso il Policlinico Gemelli IRCSS di Roma<\/strong>\u00a0\u00a0\u2013\u00a0\u00a0In primo luogo, gli oncologi americani hanno voluto rispondere a un quesito fondamentale: <strong>a chi proporre il test?\u00a0<\/strong>\u00a0Le raccomandazioni indicano che il test genetico sul sangue\u00a0\u00a0andrebbe offerto al numero pi\u00f9 alto di persone con\u00a0\u00a0nuove diagnosi di cancro della mammella,\u00a0<strong>\u00a0in particolare\u00a0\u00a0alle donne fino ai 65 anni di et\u00e0 e non fino ai 40<\/strong> anni come avviene oggi in Italia.<\/p>\n<p>\u00c8 stata infatti sottolineata l&#8217;importanza di offrire una gestione clinica personalizzata ai\/alle pazienti che presentano alterazioni dei geni BRCA1 e BRCA2 per i quali l&#8217;utilizzo di un farmaco \u00e8 in grado di fornire\u00a0\u00a0un vantaggio terapeutico&#8221;.\u00a0\u00a0Per questo <strong>il test dovrebbe essere offerto al maggior numero di persone.<\/strong> Anche le persone in et\u00e0 superiore ai 65 anni o con vecchie diagnosi dovrebbero avere accesso al test genetico nel caso in cui questo fosse importante per la loro gestione clinica. Infine, in alcuni casi potrebbe essere utile proporre anche l&#8217;analisi di altri geni. &#8220;Si tratta di un numero di persone che si fa sempre pi\u00f9 elevato: la nostra opinione \u00e8 che se anche nel nostro Paese sar\u00e0 offerto un numero cos\u00ec massiccio di test\u00a0\u00a0servir\u00e0 trovare un\u00a0\u00a0<strong>giusto compromesso tra l&#8217;aumento della soglia di et\u00e0 e il carico di lavoro dei laboratori<\/strong> \u2013 continua la prof. Lucci Cordisco &#8211; Questo aspetto indicato dall&#8217;ASCO pone la necessit\u00e0 di\u00a0\u00a0una riflessione a livello europeo e in ogni singolo paese per verificarne la possibilit\u00e0 di applicazione di questi grandi numeri\u00a0\u00a0a seconda delle peculiarit\u00e0 dei diversi\u00a0\u00a0sistemi sanitari nazionali.&#8221;<\/p>\n<p>L&#8217;utilizzo massiccio dei test in ambito oncologico pone diverse sfide ai genetisti sia dal punto di vista del laboratorio che da parte del genetista medico. &#8220;La sfida per i genetisti che emerge da questo lavoro \u00e8, a nostro avviso, l&#8217;aumento del carico di lavoro dei laboratori e delle richieste di consulenza genetiche.\u00a0\u00a0<strong>Sar\u00e0 perci\u00f2 necessario aumentare il coordinamento tra il team multisciplinare per fornire il test genetico in tempi utili, oggi di circa 4 settimane.<\/strong>\u00a0Occorre poi considerare che questo tipo di test \u00e8 diverso dagli altri esami eseguiti durante il percorso di cura \u2013 conclude la prof. Lucci Cordisco -\u2013 del\/della paziente con tumore della mammella. Non ha solo importanza per la terapia del cancro della mammella, ma pu\u00f2 identificare un rischio di poter sviluppare altri tumori non solo dei\/delle pazienti ma anche per alcuni loro familiari. Inoltre, identificarlo pu\u00f2 portare alla programmazione di una modalit\u00e0 di prevenzione adeguata all&#8217;aumentato rischio.&#8221;<\/p>\n<p>Come proporre il test genetico germinale, cio\u00e8 sul sangue, al paziente? Occorre far comprendere tutte le implicazioni. Il consenso informato richiesto prevede la firma del paziente che deve avere ben compreso la portata del test; per questo va previsto un counseling per il test genetico pre e uno post, come sottolineato dall&#8217;ASCO. Nel counseling pre-genetico vanno condivise le implicazioni del test, i possibili risultati, i suoi limiti e la utilit\u00e0 clinica con le implicazioni personali e familiari.\u00a0Nel counseling post-test vanno discussi i risultati, i rischi ad essi associati, le modalit\u00e0 di prevenzione e le indicazioni per i familiari.<\/p>\n<p>&#8220;\u00c8 importantissimo discutere il risultato del test genetico per la predisposizione ereditaria che\u00a0\u00a0definisce anche il rischio per i familiari. &#8220;Noi genetisti di SIGU siamo impegnati da anni per ottenere una corretta\u00a0\u00a0discussione con il paziente al fine di arrivare ad una corretta comprensione. \u00c8 importantissimo che i pazienti comprendano tutte queste implicazioni per poter trasmettere le indicazioni ai familiari.\u00a0\u00a0Una delle problematiche che emerge nel nostro paese \u00e8 il numero esiguo di\u00a0\u00a0questi specialisti. <strong>Con un utilizzo massiccio di test oncologici serviranno molti pi\u00f9 genetisti formati in ambito oncologico,<\/strong> che approfondiscano anche la conoscenza delle terapie oggi a disposizione in un continuo percorso di\u00a0\u00a0aggiornamento. In Italia la\u00a0\u00a0storia del genetista medico in campo oncologico \u00e8 pi\u00f9 che ventennale, perci\u00f2 \u00e8 una sfida che ci sentiamo di accogliere&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; \u00c8 uno dei temi pi\u00f9 importanti della medicina oggi: scoprire la presenza di un difetto genetico specifico (l&#8217;alterazione dei geni BRCA1 e BRCA2 ) pu\u00f2 indicare\u00a0\u00a0la terapia pi\u00f9 efficace per le donne colpite da tumore del seno. Per questo sulla prestigiosa rivista Journal of Clinical Oncology\u00a0pochi giorni fa sono stati pubblicate, dopo revisione [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":187255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-220877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=220877"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/220877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/187255"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=220877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=220877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=220877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}