{"id":221038,"date":"2024-01-18T10:00:20","date_gmt":"2024-01-18T09:00:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=221038"},"modified":"2024-01-18T10:20:01","modified_gmt":"2024-01-18T09:20:01","slug":"la-finanza-sequestra-oltre-400-litri-di-benzina-e-li-dona-in-beneficenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-finanza-sequestra-oltre-400-litri-di-benzina-e-li-dona-in-beneficenza\/","title":{"rendered":"La Finanza sequestra oltre 400 litri di benzina e li dona in beneficenza"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Il Reparto Operativo Aeronavale della Guardia di Finanza di Vibo Valentia ha donato alla Protezione Civile di Reggio Calabria <strong>circa 400 litri di benzina<\/strong>, sequestrati a bordo di<strong> un&#8217;imbarcazione sequestrata<\/strong> nel corso delle attivit\u00e0 di favoreggiamento <strong>all\u2019immigrazione clandestina<\/strong> e poi confiscati dalla Procura della Repubblica di Locri.<\/p>\n<p>In particolare, nell\u2019ambito delle attivit\u00e0 volte a prevenire e reprimere il fenomeno di favoreggiamento all\u2019immigrazione clandestina sulle coste della fascia ionica reggina, la Sezione Operativa Navale di Reggio Calabria ha operato il fermo di <strong>due scafisti,<\/strong> sequestrando un significativo quantitativo di carburante sprovvisto dei documenti attestanti la legittima provenienza, <strong>conservato in condizioni che avrebbero anche potuto arrecare grave danno alla salute<\/strong> e all\u2019incolumit\u00e0 stessa dei migranti irregolari trasportati.<\/p>\n<p>Poich\u00e9 le successive analisi di laboratorio hanno confermato la natura di prodotto petrolifero idoneo all\u2019autotrazione, le Fiamme gialle hanno proposto alla Procura della Repubblica di Locri la devoluzione ai volontari della Protezione Civile di Reggio Calabria, impegnati in numerose <strong>attivit\u00e0 di assistenza alla popolazione civile locale e nazionale<\/strong> nell\u2019ordinario e a seguito delle pi\u00f9 importanti calamit\u00e0 che spesso colpiscono i diversi territori. La proposta \u00e8 stata accolta dalla competente Autorit\u00e0 giudiziaria che, unitamente alla confisca, ha disposto l\u2019assegnazione dei circa 400 litri di benzina per finalit\u00e0 di volontariato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Il Reparto Operativo Aeronavale della Guardia di Finanza di Vibo Valentia ha donato alla Protezione Civile di Reggio Calabria circa 400 litri di benzina, sequestrati a bordo di un&#8217;imbarcazione sequestrata nel corso delle attivit\u00e0 di favoreggiamento all\u2019immigrazione clandestina e poi confiscati dalla Procura della Repubblica di Locri. In particolare, nell\u2019ambito delle attivit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":221040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-221038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=221038"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/221040"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=221038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=221038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=221038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}