{"id":221330,"date":"2024-01-22T09:51:52","date_gmt":"2024-01-22T08:51:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=221330"},"modified":"2024-01-22T09:51:52","modified_gmt":"2024-01-22T08:51:52","slug":"cosenza-prefetto-e-sindaco-salutano-il-1-reggimento-bersaglieri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-prefetto-e-sindaco-salutano-il-1-reggimento-bersaglieri\/","title":{"rendered":"Cosenza, prefetto e sindaco salutano il 1\u00b0 Reggimento Bersaglieri"},"content":{"rendered":"<p>COSENZA &#8211; Il Prefetto di Cosenza, Vittoria Ciaramella, il sindaco, Franz Caruso, ed ad altre autorit\u00e0 civili, militari e religiose della citt\u00e0 di Cosenza insieme all&#8217;Associazione Nazionale Bersaglieri (Anb), hanno salutato il 1\u00b0 reggimento bersaglieri che prossimamente sar\u00e0 impiegato in contesti operativi fuori area. Il col. <strong>Francesco Ferrara<\/strong>, comandante del 1\u00b0 reggimento bersaglieri di Cosenza, nei prossimi giorni assumer\u00e0 il comando, nei Balcani, di un <strong>contingente internazionale NATO a guida italiana.<\/strong><\/p>\n<p>Durante la cerimonia le Autorit\u00e0 presenti hanno innanzitutto ringraziato il colonnello Francesco Ferrara, comandante del 1\u00b0 reggimento bersaglieri per aver reso sempre pi\u00f9 sinergica la<strong> collaborazione tra Esercito ed Enti del territorio calabrese,<\/strong> nonch\u00e9 augurato un buon lavoro a tutti i bersaglieri per il periodo che si appresteranno a svolgere delle missioni estere.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-221331 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza.jpg\" alt=\"Bersaglieri cosenza\" width=\"526\" height=\"326\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/Bersaglieri-cosenza-356x220.jpg 356w\" sizes=\"auto, (max-width: 526px) 100vw, 526px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Prefetto di Cosenza, Vittoria Ciaramella, il sindaco, Franz Caruso, ed ad altre autorit\u00e0 civili, militari e religiose della citt\u00e0 di Cosenza insieme all&#8217;Associazione Nazionale Bersaglieri (Anb), hanno salutato il 1\u00b0 reggimento bersaglieri che prossimamente sar\u00e0 impiegato in contesti operativi fuori area. Il col. Francesco Ferrara, comandante del 1\u00b0 reggimento bersaglieri di Cosenza, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":221332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-221330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=221330"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/221332"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=221330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=221330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=221330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}