{"id":221663,"date":"2024-01-25T18:18:41","date_gmt":"2024-01-25T17:18:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=221663"},"modified":"2024-01-25T18:18:41","modified_gmt":"2024-01-25T17:18:41","slug":"arcivescovo-cosenza-che-tristezza-lautonomia-differenziata-rapani-si-difende-voto-necessario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/arcivescovo-cosenza-che-tristezza-lautonomia-differenziata-rapani-si-difende-voto-necessario\/","title":{"rendered":"Arcivescovo Cosenza: \u00abche tristezza l&#8217;Autonomia differenziata\u00bb. Rapani si difende \u00abvoto necessario\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;<strong>Che tristezza <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/autonomia-differenziata-caruso-calabria-tradita-dai-senatori-che-hanno-votato-a-favore\" target=\"_blank\" rel=\"noopener\">l&#8217;approvazione dell&#8217;autonomia differenziata in Senato<\/a><\/strong>. Ma i cristiani presenti e votanti hanno dimenticato la Scrittura, i Padri della Chiesa? Stanno dalla parte dei ricchi in maniera pregiudiziale?&#8221;. Lo scrive sui social <strong>monsignor Giovanni Checchinato, Arcivescovo metropolita di Cosenza-Bisignano<\/strong>. Checchinato, 67 anni, originario di Latina, \u00e8 arcivescovo di Cosenza dal dicembre del 2022. In precedenza era stato vescovo di San Severo. \u00c8 componente della Commissione episcopale per le migrazioni.<\/p>\n<p><strong>Rapani: &#8220;voto necessario per tutte le regioni del Sud&#8221;<\/strong><\/p>\n<p>Il Senatore cosentino<strong> Ernesto Rapani<\/strong> decide di spiegare il suo voto a favore del disegno di legge sull&#8217;autonomia differenziata in <strong>&#8220;un contesto in cui i parlamentari di centrodestra del Sud sono oggetto di contestazioni&#8221;<\/strong><\/p>\n<p>La sua decisione di votare a favore \u00e8 stata &#8220;<strong>subordinata all&#8217;inclusione di un emendamento cruciale. Proposto da Fratelli d&#8217;Italia,<\/strong> l&#8217;emendamento introduce vincoli chiari per evitare disparit\u00e0 di trattamento tra le regioni in caso di nuovi o maggiori oneri a carico della finanza pubblica. Il Senatore Rapani ha affermato che questa condizione rappresenta la <strong>massima garanzia possibile per preservare gli interessi di tutte le regioni del Sud, contribuendo a un approccio equo e bilanciato nell&#8217;ambito dell&#8217;autonomia differenziata&#8221;<\/strong>.<\/p>\n<p>&#8220;La mia scelta di votare a favore dell&#8217;approvazione del disegno di legge sull&#8217;autonomia differenziata &#8211; proesegue &#8211; \u00e8 stata guidata da una precisa valutazione delle condizioni. Il mio voto favorevole \u00e8 stato condizionato dall&#8217;inserimento dell&#8217;emendamento proposto da Fratelli d&#8217;Italia, il quale afferma chiaramente che in caso di nuovi o maggiori oneri a carico della finanza pubblica derivanti dalla determinazione dei Livelli Essenziali di Prestazione (LeP), i<strong>l trasferimento delle funzioni pu\u00f2 avvenire solo dopo l&#8217;entrata in vigore dei provvedimenti legislativi che allocano le risorse finanziarie necessarie a garantire gli stessi livelli essenziali delle prestazioni su tutto il territorio nazionale,<\/strong> comprese le regioni che non hanno sottoscritto le intese. Questa clausola \u00e8 fondamentale per evitare disparit\u00e0 di trattamento tra le regioni, mantenendo coerenza con gli obiettivi di finanza pubblica e gli equilibri di bilancio. Ritengo che questa sia la massima garanzia possibile&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Che tristezza l&#8217;approvazione dell&#8217;autonomia differenziata in Senato. Ma i cristiani presenti e votanti hanno dimenticato la Scrittura, i Padri della Chiesa? Stanno dalla parte dei ricchi in maniera pregiudiziale?&#8221;. Lo scrive sui social monsignor Giovanni Checchinato, Arcivescovo metropolita di Cosenza-Bisignano. Checchinato, 67 anni, originario di Latina, \u00e8 arcivescovo di Cosenza dal dicembre del [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":221670,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,17],"tags":[19],"class_list":["post-221663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=221663"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/221670"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=221663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=221663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=221663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}