{"id":221722,"date":"2024-01-26T13:50:51","date_gmt":"2024-01-26T12:50:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=221722"},"modified":"2024-01-26T13:50:51","modified_gmt":"2024-01-26T12:50:51","slug":"cgil-cosenza-riders-senza-tutele-meloni-contro-il-riconoscimento-dei-diritti-minimi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cgil-cosenza-riders-senza-tutele-meloni-contro-il-riconoscimento-dei-diritti-minimi\/","title":{"rendered":"Cgil Cosenza: \u00abriders senza tutele, Meloni contro il riconoscimento dei diritti minimi\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; <strong>La Cgil e Nidil Cosenza interviene sulla problematica questione dei riders<\/strong>. &#8220;Lo scorso dicembre la legge europea a tutela dei Riders \u00e8 stata bloccata dal voto sfavorevole di un blocco di paesi tra i quali la Francia, l\u2019Italia e l\u2019Ungheria di Orban. La direttiva, sostenuta dalla precedente Presidenza spagnola, sull\u2019onda delle virtuose politiche della ministra del lavoro Yolanda Diaz, riconosceva finalmente tutele e diritti ai lavoratori sfruttati dalle piattaforme.<\/p>\n<p>Il provvedimento &#8211; precisa il sindacato &#8211; prevedeva la subordinazione in presenza di indici di mancanza di autonomia, a lavoratori costretti a girare in bicicletta, a ritmi serrati, comandati dagli algoritmi e pagati a cottimo con poche manciate di Euro. <strong>Ma l\u2019Italia di Giorgia Meloni si \u00e8 opposta al riconoscimento di diritti minimi,<\/strong> c<strong>he non sono graditi ai grandi colossi economici,<\/strong> che fondano profitti di milioni e milioni di euro proprio sullo sfruttamento, sull\u2019abbattimento dei costi del lavoro, sulla detassazione favorita dal neoliberismo e sulla concorrenza sleale alle piccole e medie imprese e agli esercenti locali, ormai strozzati dalle logiche di un mercato drogato.<\/p>\n<p><strong>Ora c\u2019\u00e8 solo un mese di tempo, prima che il Parlamento europeo scada, per tentare un\u2019intesa<\/strong>. La posizione italiana non \u00e8\u2019 altro che un\u2019ulteriore conferma dell\u2019identit\u00e0 del Governo Meloni, incapace di tassare gli extra profitti e pronta invece ad ostacolare il percorso di tutela di lavoratori schiavizzati.<\/p>\n<p>Un<strong> Governo<\/strong> che spaccia l\u2019aumento della precariet\u00e0 (sono ormai oltre tre milioni i contratti a termine in Italia) per aumento dell\u2019occupazione, che n<strong>ega il salario minimo, ma favorisce l\u2019evasione fiscale<\/strong> e che \u00e8 pronta, con la legge delega del ministro Zangrillo, a negare ai lavoratori non solo diritti e rappresentanza, ma anche potere di contrattazione.\u00a0 Dopo la secessione dei ricchi tracciata dell\u2019autonomia differenziata, continua la logica che guida questo Governo: favorire il dilagare delle disuguaglianze territoriali, economiche e sociali del Paese, contro cui siamo determinati a una forte mobilitazione di cittadini e lavoratori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La Cgil e Nidil Cosenza interviene sulla problematica questione dei riders. &#8220;Lo scorso dicembre la legge europea a tutela dei Riders \u00e8 stata bloccata dal voto sfavorevole di un blocco di paesi tra i quali la Francia, l\u2019Italia e l\u2019Ungheria di Orban. La direttiva, sostenuta dalla precedente Presidenza spagnola, sull\u2019onda delle virtuose politiche [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":115282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-221722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=221722"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/221722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115282"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=221722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=221722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=221722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}