{"id":222000,"date":"2024-01-30T14:30:16","date_gmt":"2024-01-30T13:30:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222000"},"modified":"2024-01-30T14:03:14","modified_gmt":"2024-01-30T13:03:14","slug":"piscina-comunale-di-scalea-lo-scheletro-da-anni-nel-degrado-torna-allente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/piscina-comunale-di-scalea-lo-scheletro-da-anni-nel-degrado-torna-allente\/","title":{"rendered":"Piscina comunale di Scalea: lo &#8216;scheletro&#8217; da anni nel degrado torna all&#8217;Ente"},"content":{"rendered":"<p>SCALEA (CS) &#8211;<strong> L&#8217;area su cui giace ormai da pi\u00f9 di dieci anni lo scheletro della piscina comunale torner\u00e0 nella disponibilit\u00e0 del Comune di Scalea<\/strong>. <strong>Con delibera di Giunta, l&#8217;Amministrazione Perrotta ha dato mandato agli uffici di revocare la concessione all&#8217;A.I.A.S.<\/strong>, dichiarare decaduta la convenzione e, contestualmente, approntare uno studio di fattibilit\u00e0 per far si che la piscina coperta possa tornare ad essere a disposizione della collettivit\u00e0<\/p>\n<p>\u201cCi siamo trovati di fronte ad una situazione di stallo &#8211; <em>ha spiegato il sindaco Perrotta<\/em> &#8211; verso la quale abbiamo cercato soluzioni che potessero superare il contenzioso aperto ai danni del comune di Scalea per un evento funesto e dannoso. Purtroppo la decisione in primo grado difficilmente si potr\u00e0 avere nel corso del 2024, e con ogni probabilit\u00e0 la parte soccombente avr\u00e0 interesse a proporre appello ed eventuale ricorso in Cassazione, prolungando l&#8217;iter processuale di una quantit\u00e0 di anni che sommati a quelli gi\u00e0 trascorsi lascerebbero una struttura inutilizzabile e un danno d&#8217;immagine evidentissimo\u201d.<\/p>\n<h3><strong>La concessione all\u2019A.I.A.S. nel 2011<\/strong><\/h3>\n<p>Come si ricorder\u00e0 &#8211; prosegue il comune di Scalea &#8211; la concessione della piscina comunale risale all\u2019ottobre del 2011 quando <strong>la struttura fu affidata all\u2019A.I.A.S. (Associazione Italiana Assistenza agli Spastici) Sezione Cetraro<\/strong>. La concessione del servizio di gestione dell\u2019attuale complesso relativo alla piscina comunale coperta di Scalea sita in via Po Loc. Ex Campo Volo aveva la durata di 25 anni, con esclusiva finalit\u00e0 di consentire la pratica di attivit\u00e0 ricreative e sportive.<\/p>\n<p><strong>Purtroppo il 30 settembre del 2013 la piscina sub\u00ec ingenti danni, tutt\u2019oggi visibili, a causa di un evento meteorologico.<\/strong> La conseguenza fu da una parte una situazione di abbandono prima e di crescente degrado poi della struttura e dell\u2019intera area, dall\u2019altra una causa civile promossa contro il Comune di Scalea dall\u2019 A.I.A.S. che ha chiesto l\u2019accertamento di un presunto inadempimento contrattuale da parte dell\u2019ente, il risarcimento del danno, oltre alla condanna del Comune al ripristino dello stato dei luoghi.<\/p>\n<p>Sin da subito il Comune di Scalea si \u00e8 costituito in detta causa ed ha contestato l\u2019intera domanda per insussistenza del danno, tra l\u2019altro, e comunque affermando la non attribuibilit\u00e0 al Comune di alcuna responsabilit\u00e0, in relazione alla ripartizione del rischio recata nel contratto di concessione.<\/p>\n<h3><strong>Il sindaco: &#8220;verso il ripristino della struttura&#8221;<\/strong><\/h3>\n<p>\u201cAd oggi &#8211;\u00a0 <em>ha spiegato il Sindaco Perrotta<\/em> \u2013 permane lo stato di trascuratezza dell\u2019impianto e dell\u2019are che reca grave pregiudizio al pubblico decoro, anche per posizione di visibilit\u00e0 dell\u2019area. Sussiste inoltre il concreto interesse pubblico al <strong>ripristino della piena fruibilit\u00e0 del bene civico a favore della cittadinanza<\/strong>, che da oltre dieci anni non \u00e8 funzionante. In pi\u00f9 c\u2019\u00e8 da considerare che per l\u2019amministrazione sussiste specifico obbligo alla piena valorizzazione dei cespiti comunali in funzione del pubblico interesse e che la piscina comunale ricade in area demaniale marittima di propriet\u00e0 dello Stato in concessione al Comune di Scalea,<strong> per la cui occupazione l\u2019Ente corrisponde regolare canone all\u2019Erario,<\/strong> condizione che rafforza la motivazione di pubblico interesse, nell\u2019ottica del razionale utilizzo delle risorse pubbliche, perch\u00e9 si realizzi il pieno sfruttamento della struttura per le finalit\u00e0 di pubblico servizio a beneficio della comunit\u00e0 amministrata.<\/p>\n<p>Per tutti questi motivi &#8211; ha concluso il Sindaco di Scalea &#8211; non avendo in questi ultimi anni trovato un accordo transattivo percorribile per riattivare la struttura mantenendo la gestione in corso, <strong>abbiamo deciso di procedere con la revoca della concessione<\/strong> di gestione del servizio della piscina coperta alla A.I.A.S. ONLUS con conseguente decadenza della convenzione per l\u2019affidamento in gestione e dare indirizzo al Settore Tecnico comunale per la redazione di studio di fattibilit\u00e0 per un intervento di riqualificazione e connessa procedura ad evidenza pubblica per la gestione dell\u2019impianto. La volont\u00e0 e la necessit\u00e0 comune di riqualificare l&#8217;area e riconsegnare al territorio una struttura funzionale ad uso pubblico \u00e8 un&#8217;esigenza collettiva che non pu\u00f2 attendere oltre\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCALEA (CS) &#8211; L&#8217;area su cui giace ormai da pi\u00f9 di dieci anni lo scheletro della piscina comunale torner\u00e0 nella disponibilit\u00e0 del Comune di Scalea. Con delibera di Giunta, l&#8217;Amministrazione Perrotta ha dato mandato agli uffici di revocare la concessione all&#8217;A.I.A.S., dichiarare decaduta la convenzione e, contestualmente, approntare uno studio di fattibilit\u00e0 per far si [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":222001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-222000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222000"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222001"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}