{"id":222036,"date":"2024-01-31T07:57:30","date_gmt":"2024-01-31T06:57:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222036"},"modified":"2024-01-31T09:20:05","modified_gmt":"2024-01-31T08:20:05","slug":"tragico-schianto-dopo-la-festa-di-compleanno-due-vittime-e-un-ferito-grave","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tragico-schianto-dopo-la-festa-di-compleanno-due-vittime-e-un-ferito-grave\/","title":{"rendered":"Tragico schianto dopo la festa di compleanno, due vittime e un ferito grave"},"content":{"rendered":"<p>ROSARNO (RC) &#8211; \u00c8 di due persone decedute e una terza rimasta ferita gravemente, il bilancio di un incidente stradale autonomo avvenuto nella notte a Rosarno. Per cause in corso di accertamento, <strong>una Fiat 500 con a bordo tre ragazzi<\/strong> <strong>poco pi\u00f9 che ventenni<\/strong>, ha impattato violentemente con un pilastro in cemento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-222038 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02.jpg\" alt=\"incidente rosarno 2 vittime e 1 ferito 02\" width=\"404\" height=\"250\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/p>\n<p>L&#8217;urto \u00e8 stato violento e fatale per il <strong>conducente G.F., 23 anni, <\/strong>e per una <strong>ragazza sua coetanea,<\/strong> <strong>M.G. <\/strong>che si trovava seduta accanto, mentre a causa delle gravi ferite riportate, il passeggero, cugino del conducente della vettura che occupava il sedile posteriore, G.F., \u00e8 stato trasportato in <strong>codice rosso<\/strong> presso gli ospedali riuniti di Reggio Calabria. I tre stavano tornando a casa dopo aver festeggiato il <strong>compleanno della ragazza<\/strong> che ha perso la vita. Sul posto \u00e8 stato necessario l&#8217;intervento della squadra dei vigili del fuoco, per estrarre dalle lamiere contorte i tre occupanti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-222039 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03.jpg\" alt=\"incidente rosarno 2 vittime e 1 ferito 03\" width=\"488\" height=\"302\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/01\/incidente-rosarno-2-vittime-e-1-ferito-03-356x220.jpg 356w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSARNO (RC) &#8211; \u00c8 di due persone decedute e una terza rimasta ferita gravemente, il bilancio di un incidente stradale autonomo avvenuto nella notte a Rosarno. Per cause in corso di accertamento, una Fiat 500 con a bordo tre ragazzi poco pi\u00f9 che ventenni, ha impattato violentemente con un pilastro in cemento. L&#8217;urto \u00e8 stato [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":222037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-222036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222036"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222037"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}