{"id":222046,"date":"2024-01-31T11:08:11","date_gmt":"2024-01-31T10:08:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222046"},"modified":"2024-01-31T11:08:11","modified_gmt":"2024-01-31T10:08:11","slug":"la-festa-del-rugby-arriva-anche-a-vibo-valentia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/la-festa-del-rugby-arriva-anche-a-vibo-valentia\/","title":{"rendered":"La Festa del Rugby arriva anche a Vibo Valentia"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Grazie alla societ\u00e0 Meta Rugby di Vibo Valentia, in collaborazione con la Delegazione della Federazione Italiana Rugby Calabria e con il 12mo Reparto Mobile di Reggio Calabria della Polizia di Stato circa 120 ragazzi dai 6 ai 15 provenienti da tutta la Calabria hanno trascorso una giornata di sport e divertimento. Le varie under delle societ\u00e0 presenti si sono affrontate giocando a Rugby, sul campo della Polizia di Stato di Vibo Valentia. Polizia di Stato che con il proprio gruppo sportivo &#8220;Fiamme Oro&#8221; assieme alla Federazione Italiana Rugby da qualche anno promuovono il progetto &#8220;Rugby \u00e8 Legalit\u00e0&#8221; negli istituti comprensivi. Cinque in tutto le societ\u00e0 che hanno partecipato, Fiamme Oro Rugby, Cas Reggio Calabria, Rugby Rende, Spirito Santo Cosenza e Rugby Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Grazie alla societ\u00e0 Meta Rugby di Vibo Valentia, in collaborazione con la Delegazione della Federazione Italiana Rugby Calabria e con il 12mo Reparto Mobile di Reggio Calabria della Polizia di Stato circa 120 ragazzi dai 6 ai 15 provenienti da tutta la Calabria hanno trascorso una giornata di sport e divertimento. Le [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":222047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,20],"tags":[19,135],"class_list":["post-222046","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","category-sport","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222046"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222047"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}