{"id":222095,"date":"2024-01-31T19:14:38","date_gmt":"2024-01-31T18:14:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222095"},"modified":"2024-01-31T19:14:38","modified_gmt":"2024-01-31T18:14:38","slug":"corigliano-rossano-concorso-per-assumere-istruttori-di-vigilanza-a-tempo-indeterminato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/corigliano-rossano-concorso-per-assumere-istruttori-di-vigilanza-a-tempo-indeterminato\/","title":{"rendered":"Corigliano Rossano, concorso per assumere istruttori di vigilanza a tempo indeterminato"},"content":{"rendered":"<p class=\"v1MsoNormal\">CORIGLIANO-ROSSANO (CS) &#8211; <b>\u00c8 stato indetto un concorso pubblico, per titoli ed esami, finalizzato all&#8217;assunzione, a tempo pieno e indeterminato, di due posti di Istruttore di vigilanza appartenenti all&#8217;area degli &#8220;ISTRUTTORI&#8221;.<\/b>\u00a0 Tutte le comunicazioni relative al bando di concorso saranno pubblicate nel sito web del Comune di Corigliano-Rossano &#8211; Sezione Amministrazione trasparente \u2013 &#8220;Bandi e Concorsi in atto&#8221; e sul portale &#8220;inPA&#8221;, disponibile all&#8217;indirizzo internet https:\/\/www.inpa.gov.it<\/p>\n<p class=\"v1MsoNormal\">La domanda di ammissione al concorso deve essere presentata esclusivamente per via telematica, autenticandosi con SPID\/CIE\/CNS\/eIDAS. Il candidato dovr\u00e0 compilare il proprio curriculum vitae nell&#8217;apposita sezione del portale ed inoltrare il format di candidatura sulla piattaforma &#8220;inPA&#8221;.\u00a0 Per la partecipazione al concorso il candidato deve essere in possesso di un indirizzo di posta elettronica certificata (PEC) a lui intestato o di un domicilio digitale. La registrazione, la compilazione e l&#8217;invio on line della domanda devono essere completati entro il trentesimo giorno, decorrente dal giorno successivo a quello di pubblicazione del bando sul Portale &#8220;INPA&#8221;.<\/p>\n<p class=\"v1MsoNormal\"><b>Tale termine \u00e8 perentorio e sono accettate esclusivamente e indifferibilmente le domande inviate entro la data e l&#8217;orario di scadenza le ore 12 del 01\/03\/2024.<\/b><\/p>\n<p class=\"v1MsoNormal\">La data di presentazione on line della domanda di partecipazione al concorso \u00e8 certificata e comprovata da apposita ricevuta scaricabile, al termine della procedura di invio, dal Portale &#8220;inPA&#8221; che, allo scadere del termine ultimo per la presentazione della domanda, improrogabilmente non permette pi\u00f9 l&#8217;accesso alla procedura di candidatura e l&#8217;invio della domanda di partecipazione. Ai fini della partecipazione al concorso, in caso di pi\u00f9 invii della domanda di partecipazione, si terr\u00e0 conto unicamente della domanda inviata cronologicamente per ultima, intendendosi le precedenti integralmente e definitivamente revocate e private d&#8217;effetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO-ROSSANO (CS) &#8211; \u00c8 stato indetto un concorso pubblico, per titoli ed esami, finalizzato all&#8217;assunzione, a tempo pieno e indeterminato, di due posti di Istruttore di vigilanza appartenenti all&#8217;area degli &#8220;ISTRUTTORI&#8221;.\u00a0 Tutte le comunicazioni relative al bando di concorso saranno pubblicate nel sito web del Comune di Corigliano-Rossano &#8211; Sezione Amministrazione trasparente \u2013 &#8220;Bandi e [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":137745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-222095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222095"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/137745"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}