{"id":222105,"date":"2024-02-01T07:52:17","date_gmt":"2024-02-01T06:52:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222105"},"modified":"2024-02-01T07:52:17","modified_gmt":"2024-02-01T06:52:17","slug":"armi-clandestine-e-caccia-illegale-arrestati-in-flagranza-padre-e-due-figli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/armi-clandestine-e-caccia-illegale-arrestati-in-flagranza-padre-e-due-figli\/","title":{"rendered":"Armi clandestine e caccia illegale, arrestati in flagranza padre e due figli"},"content":{"rendered":"<p>STILO (RC) &#8211; I carabinieri e lo squadrone eliportato Cacciatori Calabria, nell&#8217;ambito di un servizio mirato a contrastare l&#8217;attivit\u00e0 venatoria illegale, hanno sorpreso un <strong>61enne<\/strong> e i suoi due figli, di <strong>37 e 28 anni<\/strong>, mentre cacciavano in terreni privati. I tre non avevano alcun titolo di polizia per la detenzione e il porto di armi.<\/p>\n<p>Avviate le operazioni di perquisizione sia sul posto che nell&#8217;abitazione dei tre, i militari hanno rinvenuto <strong>armi clandestine, munizioni e una modica quantit\u00e0 di sostanze stupefacenti.<\/strong> Sono state inoltre trovate due <strong>carcasse di piccoli volatili <\/strong>della precedente battuta di caccia illegale. Tratti in arresto, gli uomini si trovano agli arresti domiciliari a seguito dell&#8217;udienza di convalida da parte dell&#8217;Autorit\u00e0 giudiziaria, che provveder\u00e0 ad accertare le loro responsabilit\u00e0 nelle opportune sedi di giudizio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>STILO (RC) &#8211; I carabinieri e lo squadrone eliportato Cacciatori Calabria, nell&#8217;ambito di un servizio mirato a contrastare l&#8217;attivit\u00e0 venatoria illegale, hanno sorpreso un 61enne e i suoi due figli, di 37 e 28 anni, mentre cacciavano in terreni privati. I tre non avevano alcun titolo di polizia per la detenzione e il porto di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":222106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-222105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222105"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222106"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}