{"id":222133,"date":"2024-02-01T10:49:48","date_gmt":"2024-02-01T09:49:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222133"},"modified":"2024-02-01T12:21:48","modified_gmt":"2024-02-01T11:21:48","slug":"chiuso-il-concorsone-nella-sanita-sono-250-gli-idonei","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/chiuso-il-concorsone-nella-sanita-sono-250-gli-idonei\/","title":{"rendered":"Chiuso il &#8216;concorsone&#8217; nella sanit\u00e0, sono 250 gli idonei"},"content":{"rendered":"<p>CATANZARO &#8211; Chiuso il <a href=\"https:\/\/quicosenza.it\/news\/calabria\/lasp-catanzaro-avvia-la-fase-attuativa-del-concorsone-prove-tra-l8-e-il-16-novembre\">concorsone<\/a> per i medici e approvate le graduatorie, sono <strong>250<\/strong> i sanitari idonei su <strong>263<\/strong> posti messi a concorso da destinare all\u2019area dell\u2019emergenza urgenza intra ed extra ospedaliera in tutte le aziende sanitarie e ospedaliere della Calabria.<\/p>\n<p>Il dettaglio riguardo alle sei graduatore dei vincitori e degli idonei:<\/p>\n<p><strong>Medicina d\u2019Emergenza e Urgenza<\/strong>: posti disponibili 145<br \/>\n<strong>Vincitori<\/strong> 106: 74 specialisti e 32 in formazione.<\/p>\n<p><strong>Ortopedia e Traumatologia<\/strong>: 39 posti disponibili.<br \/>\n<strong>Vincitori<\/strong> 13, tutti in formazione specialistica.<\/p>\n<p><strong>Neurologia<\/strong>: 16 posti disponibili.<br \/>\n<strong>Vincitori<\/strong> 14: 3 specialisti e 11 in formazione.<\/p>\n<p><strong>Cardiologia<\/strong>: 9 posti disponibili.<br \/>\n51 in graduatoria: 13 specialisti e 38 in formazione.<\/p>\n<p><strong>Anestesia e Rianimazione<\/strong>: 53 posti in graduatoria.<br \/>\n58 idonei: 10 specialisti e 48 in formazione.<\/p>\n<p><strong>Neuroradiologia<\/strong>: su 1 posto disponibile 8 sono in graduatoria: 1 specialista e 7 in formazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Chiuso il concorsone per i medici e approvate le graduatorie, sono 250 i sanitari idonei su 263 posti messi a concorso da destinare all\u2019area dell\u2019emergenza urgenza intra ed extra ospedaliera in tutte le aziende sanitarie e ospedaliere della Calabria. Il dettaglio riguardo alle sei graduatore dei vincitori e degli idonei: Medicina d\u2019Emergenza e [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":222134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-222133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222133"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222134"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}