{"id":222297,"date":"2024-02-02T17:29:25","date_gmt":"2024-02-02T16:29:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222297"},"modified":"2024-02-02T17:29:25","modified_gmt":"2024-02-02T16:29:25","slug":"scuola-difficile-per-disabili-inaccessibile-e-senza-pc-in-gita-6-su-10-non-vanno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/scuola-difficile-per-disabili-inaccessibile-e-senza-pc-in-gita-6-su-10-non-vanno\/","title":{"rendered":"Scuola difficile per disabili: inaccessibile e senza PC. In gita 6 su 10 non vanno"},"content":{"rendered":"<p>ROMA &#8211; <strong>Solo il 40% degli istituti scolastici in Italia sono accessibili ai ragazzi con disabilit\u00e0 motoria<\/strong> e n<strong>el Mezzogiorno 1 scuola su 3 non dispone di un numero sufficiente di postazioni informatiche<\/strong> adattate per gli alunni con disabilit\u00e0; mentre ben 6 ragazzi disabili su 10 (7 su 10 al Sud) non possono partecipare a gite scolastiche che prevedano pernottamenti.<\/p>\n<h3>Scuola: 338mila gli allievi disabili nel 2023<\/h3>\n<p>E&#8217; una strada in salita quella che devono percorrere gli <a href=\"https:\/\/quicosenza.it\/news\/calabria\/in-calabriacs-una-scuola-su-tre-ha-necessita-di-interventi-urgenti-di-manutenzione\" target=\"_blank\" rel=\"noopener\">studenti<\/a> disabili, come racconta il r<strong>apporto Istat sull&#8217;Inclusione scolastica degli alunni con disabilit\u00e0 2022-2023<\/strong> che \u00e8 stato presentato oggi. Sono q<strong>uasi 338mila gli allievi disabili che lo scorso anno scolastico hanno frequentato le scuole<\/strong> di ogni ordine e grado, il 4,1% del totale degli iscritti, con un aumento del 7% rispetto al precedente anno.<strong> E&#8217; migliorata l&#8217;offerta di insegnanti per il sostegno<\/strong>, con un +10%. Il rapporto alunno-insegnante, pari a 1,6, \u00e8 migliore di quello previsto dalla legge, ma tra gli insegnanti 1 su 3 non ha una formazione specifica e il 12% viene assegnato in ritardo.<\/p>\n<p>Ed \u00e8 ancora forte la discontinuit\u00e0 nella didattica: <strong>il 60% degli alunni con disabilit\u00e0 cambia insegnante<\/strong> per il sostegno da un anno all&#8217;altro, <strong>il 9% nel corso dello stesso anno scolastico<\/strong>. Gli alunni con disabilit\u00e0 nelle scuole italiane <strong>sono prevalentemente maschi, 229 ogni 100 femmine<\/strong>. Il problema pi\u00f9 frequente \u00e8 la <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/disabilita-a-cosenza-il-racconto-di-casi-di-inclusione-per-costruire-buone-pratiche\" target=\"_blank\" rel=\"noopener\">disabilit\u00e0<\/a> intellettiva che riguarda il 37% degli studenti con disabilit\u00e0, quota che cresce nelle scuole secondarie di primo e secondo grado attestandosi rispettivamente al 42% e al 48%; seguono i disturbi dello sviluppo psicologico (32% degli studenti), che aumentano nelle scuole del primo ciclo, in particolare nella scuola dell&#8217;infanzia (57%).<\/p>\n<p><strong>Frequenti anche i disturbi dell&#8217;apprendimento<\/strong> e quelli dell&#8217;attenzione, ciascuno dei quali riguarda quasi un quinto degli alunni con disabilit\u00e0, entrambi sono pi\u00f9 diffusi tra gli alunni delle scuole secondarie di primo grado. E se la partecipazione all&#8217;attivit\u00e0 motoria risulta molto diffusa (92% degli alunni con disabilit\u00e0), e senza differenze rilevanti sul territorio nazionale, la musica cambia per quel che attiene le attivit\u00e0 sportive diverse da quelle rientranti nel piano della didattica curricolare, come per esempio le gare sportive: solo il 21% degli alunni con disabilit\u00e0 vi prende parte, con una partecipazione maggiore per le scuole medie (24%). Va peggio al Sud, dove partecipa solo il 17%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Solo il 40% degli istituti scolastici in Italia sono accessibili ai ragazzi con disabilit\u00e0 motoria e nel Mezzogiorno 1 scuola su 3 non dispone di un numero sufficiente di postazioni informatiche adattate per gli alunni con disabilit\u00e0; mentre ben 6 ragazzi disabili su 10 (7 su 10 al Sud) non possono partecipare a [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":222298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-222297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222297"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222298"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}