{"id":222585,"date":"2024-02-07T12:28:31","date_gmt":"2024-02-07T11:28:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222585"},"modified":"2024-02-07T12:54:09","modified_gmt":"2024-02-07T11:54:09","slug":"compra-un-gratta-e-vinci-da-5-euro-e-resta-di-sasso-i-proprietari-si-hai-vinto-500-000-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/compra-un-gratta-e-vinci-da-5-euro-e-resta-di-sasso-i-proprietari-si-hai-vinto-500-000-euro\/","title":{"rendered":"Compra un Gratta e Vinci da 5 euro e resta di sasso. I proprietari \u00absi hai vinto 500.000 euro\u00bb"},"content":{"rendered":"<p>PARTINICO (PA) &#8211; La<a href=\"https:\/\/quicosenza.it\/news\/calabria\/440526-la-dea-bendata-bacia-la-calabria-vince-5-milioni-di-euro-con-un-gratta-e-vinci\" target=\"_blank\" rel=\"noopener\"> dea bendata<\/a> questa volta arriva a <strong>Partinico, in provincia di Palermo,<\/strong> dove con un Gratta e Vinci dal costo di 5 euro, <strong>un fortunato giocatore si \u00e8 portato a casa la vincita massima di ben 500mila euro<\/strong>. \u00c8 accaduto nella <strong>tabaccheria Cangialosi<\/strong> che si trova nel centralissimo Corso dei Mille nel comune siciliano, dove adesso \u00e8 caccia al fortunato vincitore.<\/p>\n<h3>Gratta e vinci: vinto il premio massimo<\/h3>\n<p>Quando ha grattato il tagliando della Serie <strong>&#8220;<a href=\"https:\/\/www.grattaevinci.com\/classico\/il-miliardario\" rel=\"noopener\">il Miliardario<\/a>&#8221; da 5 euro<\/strong>, il giocatore \u00e8 rimasto impietrito. Come ha spiegato <strong>Gaetano Cangialosi,<\/strong> figlio del proprietario della tabaccheria, l&#8217;uomo, un gran lavoratore e una persona per bene, <strong>non credeva ai suoi occhi<\/strong> \u00ab\u00e8 rimasto di sasso e non credeva a quello che aveva appena visto. <strong>Abbiamo guardato insieme il biglietto e gli abbiamo detto che aveva vinto 500mila euro<\/strong>. Ma lui continuava ad essere incredulo e a non credere alla super vincita. Siamo davvero contenti per lui,<strong> \u00e8 un onesto lavoratore e persona perbene, lo meritava<\/strong>\u201d. La possibilit\u00e0 di vincere il premio massimo da 500mila euro \u00e8 di 1 biglietto ogni 6 milioni.<\/p>\n<h3>Il Miliardario: come si gioca<\/h3>\n<p>Si devono scoprire i <strong>\u201cNUMERI VINCENTI\u201d<\/strong> celati dall&#8217;immagine di cinque monete recanti il simbolo \u201c<strong>\u20ac<\/strong>\u201d e <strong>\u201cI TUOI NUMERI\u201d<\/strong>, celati dall\u2019immagine di quindici blocchetti di banconote. Se ne \u201c<strong>I TUOI NUMERI\u201d<\/strong> si trovano, una o pi\u00f9 volte, uno o pi\u00f9 <strong>\u201cNUMERI VINCENTI\u201d<\/strong> si vince il premio o la somma dei premi corrispondenti. Se ne <strong>\u201cI TUOI NUMERI\u201d<\/strong> si trova: il <strong>simbolo della stella<\/strong> si vince un premio di importo pari a 100\u20ac. Se si trova <strong>il simbolo del ferro di cavallo<\/strong> si vince un premio di importo pari a 200\u20ac. Se si trova invece <strong>il simbolo della moneta<\/strong> si vince un premio di importo pari a 500\u20ac. infine se si trova <strong>il simbolo del lingotto<\/strong> si vincono tutti i premi presenti nell\u2019area di gioco<\/p>\n<p><strong>Vincita massima:<\/strong>\u00a0\u20ac 500.000,00 euro<\/p>\n<p><strong>Altri premi (in euro):<\/strong>\u00a05,00 &#8211; 10,00 &#8211; 15,00 &#8211; 20,00 &#8211; 50,00 &#8211; 100,00 &#8211; 200,00 &#8211; 500,00 &#8211; 1.000,00 &#8211; 10.000,00 &#8211; 100.000,00 &#8211; 300.000,00<br \/>\n<strong>Probabilit\u00e0 di vincita:<\/strong>\u00a01 biglietto ogni 7,84\u00a0(premi superiori al costo della giocata)<br \/>\n<strong>Probabilit\u00e0 di vincita massima:<\/strong> 1 biglietto ogni 6.000.000<br \/>\n<strong>Probabilit\u00e0 di vincita nel dettaglio:<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARTINICO (PA) &#8211; La dea bendata questa volta arriva a Partinico, in provincia di Palermo, dove con un Gratta e Vinci dal costo di 5 euro, un fortunato giocatore si \u00e8 portato a casa la vincita massima di ben 500mila euro. \u00c8 accaduto nella tabaccheria Cangialosi che si trova nel centralissimo Corso dei Mille nel [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":222587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-222585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222585"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222587"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}