{"id":222681,"date":"2024-02-11T08:00:04","date_gmt":"2024-02-11T07:00:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222681"},"modified":"2024-02-08T11:05:30","modified_gmt":"2024-02-08T10:05:30","slug":"asaps-22-vittime-della-strada-nellultimo-fine-settimana-anche-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/asaps-22-vittime-della-strada-nellultimo-fine-settimana-anche-in-calabria\/","title":{"rendered":"Asaps: 22 vittime della strada nell&#8217;ultimo fine settimana, anche in Calabria"},"content":{"rendered":"<p>BOLOGNA &#8211; Una sorta di bollettino di guerra solo quello tra venerd\u00ec 2 e domenica 4 febbraio scorsi. Sono state ben 22 le vittime sulle strade italiane per incidenti, in leggero aumento rispetto al fine settimana precedente (20). Lo ricorda l&#8217;Asaps, Associazione sostenitori e amici della polizia stradale. <strong>La vittima pi\u00f9 giovane un ragazzo di 19 anni, quella pi\u00f9 anziana un uomo di 89 anni<\/strong>. Sono deceduti 13 automobilisti, sei motociclisti, un pedone, un ciclista e un autotrasportatore.<\/p>\n<p>Si sono verificati anche <strong>due incidenti plurimortali, con quattro vittime<\/strong>. Nel report \u00e8 considerato il decesso di una donna di 35 anni rimasta gravemente ferita in un incidente sette giorni fa: Asaps ha scelto di conteggiare, quando ne viene a conoscenza, anche i decessi che avvengono successivamente e oltre i 30 giorni dal sinistro, perch\u00e9 si tratta sempre di vittime della strada.<\/p>\n<p>La fuoriuscita del veicolo senza il coinvolgimento di terzi \u00e8 stata la causa di sette incidenti fatali, dieci quelli avvenuti su strade statali e provinciali, uno in autostrada. Fra le 22 vittime, cinque avevano meno di 35 anni. Sono stati 6 i decessi in Emilia-Romagna, 4 in Puglia, 3 in Lombardia, 2 in Campania e Sicilia, <strong>uno<\/strong> in Veneto, Lazio, Abruzzo, <strong>Calabria<\/strong>, Sardegna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOLOGNA &#8211; Una sorta di bollettino di guerra solo quello tra venerd\u00ec 2 e domenica 4 febbraio scorsi. Sono state ben 22 le vittime sulle strade italiane per incidenti, in leggero aumento rispetto al fine settimana precedente (20). Lo ricorda l&#8217;Asaps, Associazione sostenitori e amici della polizia stradale. La vittima pi\u00f9 giovane un ragazzo di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":218600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-222681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222681"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/218600"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}