{"id":22280,"date":"2013-05-15T11:31:10","date_gmt":"2013-05-15T09:31:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22280"},"modified":"2023-01-17T13:19:55","modified_gmt":"2023-01-17T12:19:55","slug":"8714-lo-celso-l-anarchico-dello-spirito-santo-ucciso-dai-servizi-segreti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8714-lo-celso-l-anarchico-dello-spirito-santo-ucciso-dai-servizi-segreti\/","title":{"rendered":"Lo Celso l\u2019anarchico dello Spirito Santo \u2018ucciso\u2019 dai servizi segreti"},"content":{"rendered":"<p>COSENZA \u2013 Cosenza Vecchia non archivia. Anzi. Oggi all\u2019Auser di piazza Spirito Santo il Movimento Disoccupati ricorda l\u2019anarchico cosentino morto misteriosamente nel 1970 insieme a quattro compagni in un \u2018anomalo\u2019 incidente stradale.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">I cinque, conosciuti come gli Anarchici della Baracca, persero la vita travolti da un camion in austostrada tra Ferentino e Frosinone a 58 chilometri da Roma. In viaggio per la Capitale per consegnare alle autorit\u00e0 un dossier che scoperchiava la collaborazione tra Stato, \u2018Ndrangheta e servizi segreti deviati nella rivolta di Reggio nell\u2019estate del \u201970 e il deragliamento del Treno del Sole a Gioia Tauro. Il documento spar\u00ec nel nulla. Il camion si rivel\u00f2 essere di propriet\u00e0 di un\u2019azienda del \u2018principe nero\u2019, Junio Valerio Borghese l\u2019ex fascista comandante della X Mas che guid\u00f2 il colpo di Stato, il famoso Golpe Borghese, avvenuto pochi mesi dopo la morte dei giovani. Una coincidenza che ha destato diversi sospetti negli ambienti militanti, ma non nella magistratura che non esit\u00f2 ad archiviare frettolosamente il caso dei cinque anarchici. I nomi di Luigi Lo Celso, Gianni Aric\u00f2, Annalise Borth, Angelo Casile e Franco Scordo periti nell\u2019incidente risuon\u00f2 nelle aule di Tribunale quando due pentiti ex affiliati alle cosche del reggino, Giacomino Lauro e Carmine Dominici, parlarono della collusione tra gli ambienti della destra eversiva e la \u2018ndrangheta confermando la responsabilit\u00e0 di questi sia nelle rivolte reggine sia nell\u2019attentato di Gioia Tauro. Lo stesso Dominici rivel\u00f2 al giudice in aula di ritenere che \u201cquello dei cinque ragazzi non sia stato un incidente ma un omicidio\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Un presunto omicidio che sar\u00e0 oggi al centro <strong>del dibattito pubblico che si terr\u00e0 oggi alle 18.30 all\u2019Auser con la presenza di Eva Catizone, Andrea Arcuri segretario del Movimento Disoccupati e Gianfranco Bonofiglio direttore de \u201cLa voce cosentna\u201d. A seguire le note di Daniele Gabriele, del Trio Kum\u00e8 Jazz e dei Musicanti del Vento faranno da cornice alla giornata in ricordo dei cinque giovani eroi calabresi.<\/strong> Eroi che la citt\u00e0 di Cosenza non intende dimenticare. Sono infatti diverse le realt\u00e0 militanti che da febbraio hanno avviato una raccolta firme affinch\u00e9 si possibile chiedere ufficialmente al Comune l\u2019intitolazione di una strada a Luigi Lo Celso proprio nel suo quartiere d\u2019origine: lo Spirito Santo.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Cosenza Vecchia non archivia. Anzi. Oggi all\u2019Auser di piazza Spirito Santo il Movimento Disoccupati ricorda l\u2019anarchico cosentino morto misteriosamente nel 1970 insieme a quattro compagni in un \u2018anomalo\u2019 incidente stradale.<\/p>\n","protected":false},"author":22,"featured_media":22281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-22280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22280"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22281"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}