{"id":222832,"date":"2024-02-09T19:36:38","date_gmt":"2024-02-09T18:36:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222832"},"modified":"2024-02-09T20:01:51","modified_gmt":"2024-02-09T19:01:51","slug":"grave-incidente-sulla-statale-18-tra-paola-e-san-lucido-maxi-tamponamento-e-diversi-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/grave-incidente-sulla-statale-18-tra-paola-e-san-lucido-maxi-tamponamento-e-diversi-feriti\/","title":{"rendered":"Grave incidente sulla statale 18 tra Paola e San Lucido: maxi tamponamento e diversi feriti"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Un grave incidente si \u00e8 verificato lungo la strada Statale 18 &#8220;Tirrena Inferiore&#8221;<\/strong>, nel tardo pomeriggio di oggi, nei pressi del <strong>carcere penitenziario tra Paola e San Lucido<\/strong> all\u2019altezza del km 320,800 in zona Deuda. Secondo cause da accertare, <strong>il violento scontro ha coinvolto sei auto <\/strong>provocando un maxi tamponamento.<\/p>\n<p><strong>Pi\u00f9 di un&#8217;ambulanza \u00e8 giunta sul posto per soccorrere diversi feriti (almeno 4)<\/strong> di cui <strong>due sarebbero in gravi condizioni<\/strong>. Sul posto i Carabinieri di Paola, il personale della Polizia stradale, sanitari del 118 di Amantea e di Paola e i<strong> vigili del fuoco, che hanno dovuto estrarre dalle lamiere contorte alcuni feriti<\/strong>. Al momento il traffico \u00e8 bloccato in entrambe le direzioni e sul posto \u00e8 presente anche il personale Anas per il ripristino della viabilit\u00e0.<\/p>\n<p><em>In aggiornamento<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un grave incidente si \u00e8 verificato lungo la strada Statale 18 &#8220;Tirrena Inferiore&#8221;, nel tardo pomeriggio di oggi, nei pressi del carcere penitenziario tra Paola e San Lucido all\u2019altezza del km 320,800 in zona Deuda. Secondo cause da accertare, il violento scontro ha coinvolto sei auto provocando un maxi tamponamento. Pi\u00f9 di un&#8217;ambulanza [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":222834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-222832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222832"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222834"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}