{"id":222863,"date":"2024-02-10T12:38:49","date_gmt":"2024-02-10T11:38:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=222863"},"modified":"2024-02-10T12:38:49","modified_gmt":"2024-02-10T11:38:49","slug":"danneggiata-lauto-di-don-felice-palamara-parroco-di-pannaconi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/danneggiata-lauto-di-don-felice-palamara-parroco-di-pannaconi\/","title":{"rendered":"Danneggiata l\u2019auto di don Felice Palamara, parroco di Pannaconi"},"content":{"rendered":"<p>VIBO VALLENTIA &#8211; Gravissimo atto intimidatorio nel Vibonese. L\u2019auto di Don Felice Palamara, parroco di Pannaconi di Cessaniti, <strong>\u00e8 stata danneggiata con un taglierino che ha lasciato delle croci incise sul telaio<\/strong>.<\/p>\n<p>Un episodio che si aggiunge alle minacce e agli insulti ricevuti dal sacerdote tramite lettere minatorie sin dal mese di settembre. <strong>La comunit\u00e0 di Pannaconi ha mostrato solidariet\u00e0 nei confronti del loro pastore, che ha sporto denuncia ai carabinieri. <\/strong>\u00abSiamo indignati, non permetteremo a nessuno di fargli del male\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALLENTIA &#8211; Gravissimo atto intimidatorio nel Vibonese. L\u2019auto di Don Felice Palamara, parroco di Pannaconi di Cessaniti, \u00e8 stata danneggiata con un taglierino che ha lasciato delle croci incise sul telaio. Un episodio che si aggiunge alle minacce e agli insulti ricevuti dal sacerdote tramite lettere minatorie sin dal mese di settembre. La comunit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":222864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-222863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=222863"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/222863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/222864"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=222863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=222863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=222863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}