{"id":223010,"date":"2024-02-13T07:10:40","date_gmt":"2024-02-13T06:10:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=223010"},"modified":"2024-02-13T07:10:40","modified_gmt":"2024-02-13T06:10:40","slug":"violento-incidente-a-corigliano-rossano-quattro-feriti-tra-cui-un-bambino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/violento-incidente-a-corigliano-rossano-quattro-feriti-tra-cui-un-bambino\/","title":{"rendered":"Violento incidente a Corigliano Rossano, quattro feriti tra cui un bambino"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; L&#8217;impatto si \u00e8 verificato ieri sera nell&#8217;area coriglianese di <strong>Villaggio Frassa<\/strong> ed ha visto coinvolte due vetture, una delle quali si \u00e8 ribaltata. Tra le persone a bordo dei mezzi anche un <strong>bambino<\/strong> che <strong>non sarebbe comunque in gravi condizioni<\/strong>. Ancora in corso di accertamento le cause dello scontro che sarebbe stato frontale. Quattro le persone rimaste ferite, <strong>nessuna in modo grave<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; L&#8217;impatto si \u00e8 verificato ieri sera nell&#8217;area coriglianese di Villaggio Frassa ed ha visto coinvolte due vetture, una delle quali si \u00e8 ribaltata. Tra le persone a bordo dei mezzi anche un bambino che non sarebbe comunque in gravi condizioni. Ancora in corso di accertamento le cause dello scontro che sarebbe [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":220080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-223010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/223010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=223010"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/223010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/220080"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=223010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=223010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=223010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}