{"id":223402,"date":"2024-02-16T18:24:56","date_gmt":"2024-02-16T17:24:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=223402"},"modified":"2024-02-16T18:24:56","modified_gmt":"2024-02-16T17:24:56","slug":"allannunziata-100-interventi-con-il-da-vinci-il-robot-che-evita-il-tremore-naturale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/allannunziata-100-interventi-con-il-da-vinci-il-robot-che-evita-il-tremore-naturale\/","title":{"rendered":"All&#8217;Annunziata 100 interventi con il &#8216;Da Vinci&#8217;, il robot che evita il tremore naturale"},"content":{"rendered":"<p>COSENZA &#8211; Sono 100 gli interventi eseguiti, ad oggi, con il robot Da Vinci. A distanza di nove mesi \u2013 il primo intervento fu eseguito il 16 maggio 2023 &#8211; la chirurgia robotica stacca il primo tagliando e segna il primo traguardo.<\/p>\n<p>Cambiano i setting operatori di <strong>Urologia, Ginecologia e Chirurgia generale<\/strong>: il Da Vinci\u00a0 <strong>replica i gesti eseguiti dal chirurgo alla console<\/strong><strong>, <\/strong>ma permette di<strong>\u00a0operare con maggiore precisione<\/strong>\u00a0grazie alla\u00a0soppressione\u00a0del\u00a0tremore\u00a0naturale delle mani e alla\u00a0possibilit\u00e0\u00a0di\u00a0<strong>moltiplicare i movimenti<\/strong>.<\/p>\n<p>Ad un anno dalla sigla del\u00a0 Protocollo con Unical si registrano i primi risultati nella direzione del miglioramento dei servizi sanitari sul territorio, dell\u2019incremento dell\u2019offerta di cure e salute e nell\u2019 inversione del trend di migrazione sanitaria.<\/p>\n<p>La geografia del nuovo Atto Aziendale rafforza questi successi e il progetto <strong>di crescita e rilancio dell\u2019ospedale Annunziata \u00a0\u00a0che trasformer\u00e0, l\u2019hub di Cosenza in policlinico universitario<\/strong>.<\/p>\n<p><em>\u00a0\u00a0 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Sono 100 gli interventi eseguiti, ad oggi, con il robot Da Vinci. A distanza di nove mesi \u2013 il primo intervento fu eseguito il 16 maggio 2023 &#8211; la chirurgia robotica stacca il primo tagliando e segna il primo traguardo. Cambiano i setting operatori di Urologia, Ginecologia e Chirurgia generale: il Da Vinci\u00a0 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":198829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-223402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/223402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=223402"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/223402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/198829"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=223402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=223402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=223402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}