{"id":223492,"date":"2024-02-18T10:26:08","date_gmt":"2024-02-18T09:26:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=223492"},"modified":"2024-02-18T10:28:04","modified_gmt":"2024-02-18T09:28:04","slug":"rifiuti-abbandonati-su-un-terreno-e-dati-alle-fiamme-rischio-inalazioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rifiuti-abbandonati-su-un-terreno-e-dati-alle-fiamme-rischio-inalazioni\/","title":{"rendered":"Rifiuti abbandonati su un terreno e dati alle fiamme, rischio inalazioni"},"content":{"rendered":"<p>PARGHELIA (VV) &#8211; Intervento dei carabinieri Forestali a Parghelia, localit\u00e0 della <strong>Costa degli Dei<\/strong>, all\u2019interno di un\u2019area di propriet\u00e0 comunale di circa 400 metri quadri. Sul terreno numerosi rifiuti abbandonati che sono stati dati alle fiamme, tra cui <strong>plastica<\/strong>. I fumi inalati rischiano di <strong>provocare un avvelenamento da sostanze chimiche tossiche<\/strong> e danni alla trachea, alle vie respiratorie e ai polmoni, in quanto si vanno a liberare nell\u2019atmosfera sostanze pericolose quali <strong>diossine<\/strong> e idrocarburi policiclici aromatici (Ipa).<\/p>\n<p>\u00abIl rischio che l\u2019incolumit\u00e0 umana corre quando viene perpetrato un simile reato \u00e8 molto alto \u2013 sottolineano i militari forestali \u2013 per questo \u00e8 fondamentale che<strong> tutta la comunit\u00e0 si adoperi per denunciare prontamente tali condotte\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARGHELIA (VV) &#8211; Intervento dei carabinieri Forestali a Parghelia, localit\u00e0 della Costa degli Dei, all\u2019interno di un\u2019area di propriet\u00e0 comunale di circa 400 metri quadri. Sul terreno numerosi rifiuti abbandonati che sono stati dati alle fiamme, tra cui plastica. I fumi inalati rischiano di provocare un avvelenamento da sostanze chimiche tossiche e danni alla trachea, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":223493,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-223492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/223492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=223492"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/223492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/223493"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=223492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=223492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=223492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}