{"id":22380,"date":"2013-05-16T13:21:46","date_gmt":"2013-05-16T11:21:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22380"},"modified":"2023-01-17T13:20:02","modified_gmt":"2023-01-17T12:20:02","slug":"8766-maltempo-forti-raffiche-di-vento-chiusa-la-s-s-18","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8766-maltempo-forti-raffiche-di-vento-chiusa-la-s-s-18\/","title":{"rendered":"Maltempo: forti raffiche di vento chiusa la S.S. 18"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">CATANZARO &#8211; Forti raffiche di vento hanno costretto l&#8217;Anas&nbsp;<\/span><span style=\"color: #000000;\">ha chiudere provvisoriamente al traffico la strada 18 &#8216;Tirrena Inferiore&#8217;, tra i chilometri 357 <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">e 360. Il forte vento ha scoperto una tettoia di un lido balneare tra Nocera Terinese e Falerna.&nbsp;Sul posto sono presenti uomini e mezzi dell&#8217;Anas e delle forze dell&#8217;ordine per ripristinare la viabilita&#8217;. Sempre sulla statale 18, dal chilometro 349,650 al chilometro 379,000, ci sono forti rallentamenti sempre a causa del vento.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Forti raffiche di vento hanno costretto l&#8217;Anas&nbsp;ha chiudere provvisoriamente al traffico la strada 18 &#8216;Tirrena Inferiore&#8217;, tra i chilometri 357<\/p>\n","protected":false},"author":22,"featured_media":22381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-22380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22380"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22381"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}