{"id":224290,"date":"2024-02-28T11:10:17","date_gmt":"2024-02-28T10:10:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224290"},"modified":"2024-02-28T16:30:56","modified_gmt":"2024-02-28T15:30:56","slug":"gratta-e-vinci-jackpot-da-2-milioni-con-un-biglietto-da-10-euro-e-sei-vincite-da-500mila-euro-ecco-dove","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/gratta-e-vinci-jackpot-da-2-milioni-con-un-biglietto-da-10-euro-e-sei-vincite-da-500mila-euro-ecco-dove\/","title":{"rendered":"Gratta e vinci, jackpot da 2 milioni con un biglietto da 10 euro e sei vincite da 500mila euro &#8211; ecco dove"},"content":{"rendered":"<p>COLONNELLA (TE) &#8211; Nuova <a href=\"https:\/\/quicosenza.it\/news\/italia\/gratta-e-vinci-milionario-compra-un-biglietto-nuovo-50x-da-10-euro-vince-2-milioni-di-euro\" target=\"_blank\" rel=\"noopener\">vincita<\/a> milionaria al Gratta e Vinci. Dopo i sette milioni di euro vinti nel giro di pochi giorni in due comuni della Campania: 5 milioni a <a href=\"https:\/\/quicosenza.it\/news\/italia\/compra-un-gratta-e-vinci-da-20-euro-e-diventa-milionario-premio-da-5-milioni-forse-ad-un-operaio\">Domicella<\/a> in provincia di Avellino con il tagliando \u00abNuovo 100X\u00bb e 2 milioni di euro che un fortunato giocatore ha vinto a Caivano in corso Umberto 93, nella settimana dal <strong>19 al 25 febbraio sono stati vinti altri due milioni di euro<\/strong>. <strong>La dea Bendata \u00e8 arrivata in Abruzzo esattamente a Colonnella in provincia di Teramo<\/strong>. Il fortunato giocatore ha acquistato il biglietto del Gratta e vinci della serie Il <a href=\"https:\/\/www.grattaevinci.com\/classico\/il-miliardario-mega\" rel=\"noopener\">Miliardario Mega<\/a> <strong>dal costo di 10 ero ed ha vinto il premio massimo per questo tipo di tagliando: ovvero 2 milioni di euro<\/strong>.Un risultato che si rivela come uno dei premi pi\u00f9 cospicui mai registrati nella zona. Ovviamente \u00e8 partita la caccia al fortunato vincitore.<\/p>\n<h3>Top vincite della settimana: sei biglietti da 500mila euro<\/h3>\n<p>Fin qui i premi milionari. Ma nell&#8217;ultima settimana si sono registrate anche <strong>sei vincite da 500mila euro in tutta Italia, <\/strong>da Nord a Sud. Due in Puglia a <strong>Foggia e Taranto<\/strong> con il tagliando &#8220;Il Miliardario&#8221; e &#8220;Ultra Numerissimi&#8221;. A<strong> Brescia<\/strong> con il tagliando &#8220;Il Miliardario&#8221;, a <strong>Scandiano (Reggio Emilia)<\/strong> con il tagliando &#8220;il Miliardario Mega&#8221;, a <strong>Ripalta Cremasca (Cremona)<\/strong> con il tagliando &#8220;Nuovo Doppia Sfida&#8221;\u00a0 e a <strong>San Giovanni (MI)<\/strong> con il Gratta e vinci della serie &#8220;Numerissimi&#8221;.<\/p>\n<div id=\"attachment_224293\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-224293\" class=\" wp-image-224293\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana.jpg\" alt=\"Top vincite della settimana Gratta e Vinci\" width=\"500\" height=\"372\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana.jpg 799w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-300x223.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-768x572.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-150x112.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-485x360.jpg 485w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-696x518.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-564x420.jpg 564w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-80x60.jpg 80w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/02\/Top-vincite-della-settimana-265x198.jpg 265w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-224293\" class=\"wp-caption-text\">Le top vincite milionarie dell&#8217;ultima settimana<\/p><\/div>\n<h3>Gratta e vinci, come funziona il Miliardario Mega<\/h3>\n<p>Si devono scoprire i\u00a0\u201c<strong>Numeri vincenti\u201d\u00a0il\u00a0\u201cNumero Jolly\u201d\u00a0ed\u00a0\u201cI tuoi numeri\u201d.<\/strong> Se si trova una o pi\u00f9 volte, uno o pi\u00f9\u00a0\u201c<strong>Numeri vincenti\u201d\u00a0<\/strong>ne\u00a0<strong>\u201cI tuoi numeri\u201d\u00a0si vince il premio o la somma dei premi corrispondenti.<\/strong> Se ne \u201cI tuoi numeri\u201d si trova il simbolo \u201cferro di cavallo\u201d si vincono 200 euro.. Se ne \u201cI tuoi numeri\u201d si trova il \u201cNumero jolly\u201d si vince 10 volte il premio corrispondente.<br \/>\n<strong>Costo del biglietto:<\/strong>\u00a010 Euro<br \/>\n<strong>Vincita massima:<\/strong>\u20ac 2.000.000,00<br \/>\n<strong>Altri premi (in euro):<\/strong><br \/>\n10 \u20ac\u2013 20 \u20ac \u2013 25 \u20ac \u2013 50 \u20ac \u2013 100 \u20ac \u2013 200 \u20ac- 500 \u20ac- 1.000 \u20ac- 10.000 \u20ac &#8211; 20.000 \u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COLONNELLA (TE) &#8211; Nuova vincita milionaria al Gratta e Vinci. Dopo i sette milioni di euro vinti nel giro di pochi giorni in due comuni della Campania: 5 milioni a Domicella in provincia di Avellino con il tagliando \u00abNuovo 100X\u00bb e 2 milioni di euro che un fortunato giocatore ha vinto a Caivano in corso [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":134643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-224290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224290"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/134643"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}