{"id":224552,"date":"2024-03-02T17:25:53","date_gmt":"2024-03-02T16:25:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224552"},"modified":"2024-03-02T17:25:53","modified_gmt":"2024-03-02T16:25:53","slug":"uccide-il-padre-a-coltellate-18enne-in-arresto-stanca-delle-violenze-subite","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/uccide-il-padre-a-coltellate-18enne-in-arresto-stanca-delle-violenze-subite\/","title":{"rendered":"Uccide il padre a coltellate, 18enne in arresto: \u00abstanca delle violenze subite\u00bb"},"content":{"rendered":"<p>ASTI &#8211; Dramma ieri sera a Nizza Monferrato, nell&#8217;Astigiano, dove una <strong>18enne Makka Sulaev \u00e8 stata arrestata per aver accoltellato e ucciso il padre Akhyad, 50 anni<\/strong>. La famiglia &#8211; mamma e tre fratelli pi\u00f9 piccoli &#8211; \u00e8 immigrata in Piemonte alcuni anni fa, proveniente dal Caucaso. Sono musulmani osservanti, tanto che Makka anche ieri sera indossava il hijab, secondo quanto riporta l&#8217;Agi.<\/p>\n<p>\u201cL\u2019ho ucciso.\u00a0<strong>Tutti in casa subivamo le sue violenze<\/strong>, soprattutto mia mamma\u201c, avrebbe confessato la giovane dopo un\u2019intera notte di interrogatorio davanti ai magistrati. Tra le ipotesi al vaglio degli inquirenti quella che Makka abbia agito per difendersi dunque dalla violenza del padre o per difendere la madre.<\/p>\n<p>Secondo quanto si apprende, l&#8217;uomo si era appena licenziato dal lavoro di lavapiatti. L&#8217;uomo \u00e8 stato colpito all&#8217;addome. Soccorso dai medici del 118, \u00e8 morto poco dopo. I carabinieri, giunti sul posto, hanno trovato Makka nell\u2019appartamento, <strong>impietrita e sotto shock<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASTI &#8211; Dramma ieri sera a Nizza Monferrato, nell&#8217;Astigiano, dove una 18enne Makka Sulaev \u00e8 stata arrestata per aver accoltellato e ucciso il padre Akhyad, 50 anni. La famiglia &#8211; mamma e tre fratelli pi\u00f9 piccoli &#8211; \u00e8 immigrata in Piemonte alcuni anni fa, proveniente dal Caucaso. Sono musulmani osservanti, tanto che Makka anche ieri [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":210212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-224552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224552"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/210212"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}