{"id":224657,"date":"2024-03-04T19:27:13","date_gmt":"2024-03-04T18:27:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224657"},"modified":"2024-03-04T19:27:13","modified_gmt":"2024-03-04T18:27:13","slug":"uccise-il-padre-e-lo-seppelli-nel-bosco-20-anni-di-carcere-per-walter-loielo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/uccise-il-padre-e-lo-seppelli-nel-bosco-20-anni-di-carcere-per-walter-loielo\/","title":{"rendered":"Uccise il padre e lo seppell\u00ec nel bosco: 20 anni di carcere per Walter Loielo"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Il gip di Vibo Valentia, Barbara Borelli, ha condannato a<strong> 20 anni di reclusione,<\/strong> con l&#8217;accusa di omicidio, occultamento di cadavere e reati in materia di armi, il collaboratore di giustizia<strong> Walter Loielo, accusato dell&#8217;omicidio del padre Antonino, vittima di lupara bianca nell&#8217;aprile 2017<\/strong>. Le indagini, coordinate dal procuratore di Vibo Valentia Camillo Falvo e dal pm Filomena Aliberti e condotte dalla Squadra mobile, avevano condotto al <strong>rinvenimento del corpo della vittima nel 2020,<\/strong> seppellito in una zona impervia tra la boscaglia, nella frazione Ariola di Gerocarne. Secondo l&#8217;accusa, il movente \u00e8 da ricondurre a vicende di carattere familiare.<\/p>\n<h3><strong>Le indagini riaperte dopo il pentimento di Walter Loielo<\/strong><\/h3>\n<p>A suo tempo fu stralciata la posizione di un altro figlio della vittima, Ivan, giudicato in un separato procedimento. Walter Loielo \u00e8 stato assistito dall&#8217;avvocato Antonia Nicolini. U<strong>na vicenda camuffata da allontanamento volontario della vittima<\/strong> che, qualche tempo prima, insieme gli stessi figli, era scampato ad un agguato. Le indagini sulla sparizione di Antonino Loielo, all&#8217;epoca non portarono a nulla, ma furono riaperte dopo il <strong>pentimento di Walter.<\/strong> Il capofamiglia fu portato in una zona isolata dell&#8217;Ariola, impervia e costellata da fitta vegetazione, boscaglia e sentieri inaccessibili ai veicoli, <strong>ucciso a colpi di pistola e sepolto in un sacco di cellophane<\/strong> sotto la carcassa di una vecchia 500 rossa che si trovava l\u00ec da anni.<\/p>\n<h3><strong>Antonino Loielo scampato ad un agguato nel 2015<\/strong><\/h3>\n<p>Antonino Loielo era cugino dei fratelli Vincenzo e Giuseppe Loielo, che tra la seconda met\u00e0 degli anni &#8217;90 e gli inizi del 2000 dominavano il vasto comprensorio montano. Vennero uccisi nel pomeriggio del 22 aprile del 2002 da un commando formato, secondo l&#8217;accusa, dal gruppo facente capo a<strong> Bruno Emanuele, boss di Soriano e Sorianello<\/strong>. Antonino, poi, scamp\u00f2 ad un agguato la sera del 23 ottobre 2015 in localit\u00e0 &#8220;Castania&#8221; quando l&#8217;auto sulla quale viaggiava insieme alla famiglia fu raggiunta da alcuni colpi di fucile. L&#8217;allora 48enne, venne raggiunto al sopracciglio destro ed al torace, la compagna al braccio destro, mentre il figlio Alex, 22 anni, alla mandibola da un proiettile rimasto ritenuto. Miracolosamente illesi, invece, gli altri due figli minorenni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Il gip di Vibo Valentia, Barbara Borelli, ha condannato a 20 anni di reclusione, con l&#8217;accusa di omicidio, occultamento di cadavere e reati in materia di armi, il collaboratore di giustizia Walter Loielo, accusato dell&#8217;omicidio del padre Antonino, vittima di lupara bianca nell&#8217;aprile 2017. Le indagini, coordinate dal procuratore di Vibo Valentia [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":224658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-224657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224657"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/224658"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}