{"id":224687,"date":"2024-03-05T10:12:40","date_gmt":"2024-03-05T09:12:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224687"},"modified":"2024-03-05T10:12:40","modified_gmt":"2024-03-05T09:12:40","slug":"unical-ricerca-medici-altamente-qualificati-per-un-ruolo-in-ateneo-ospedale-e-inrca-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/unical-ricerca-medici-altamente-qualificati-per-un-ruolo-in-ateneo-ospedale-e-inrca-cosenza\/","title":{"rendered":"Unical ricerca medici altamente qualificati per un ruolo in ateneo, ospedale e Inrca Cosenza"},"content":{"rendered":"<p>RENDE (CS) &#8211; <strong>Cresce sempre di pi\u00f9 la squadra di docenti medici altamente qualificati che l\u2019Unical arruola per formare i futuri medici e per offrire assistenza d\u2019eccellenza nella sanit\u00e0 locale<\/strong>. Dopo il grande interesse mostrato da professori affermati in Italia e all\u2019estero nella precedente call, l\u2019ateneo ha deciso di aprire una nuova manifestazione di interesse in area medica. La procedura prevede l\u2019assunzione di altri <strong>professionisti che insegneranno <\/strong>nel corso di laurea in Medicina e chirurgia e Tecnologie digitali e che avranno un ruolo, che potrebbe essere anche apicale<strong> in alcuni reparti gi\u00e0 definiti a guida universitaria, presso l\u2019Azienda ospedaliera e l\u2019Irccs &#8211; Inrca di Cosenza.<\/strong><\/p>\n<h3><strong>La nuova call per medici professionisti<\/strong><\/h3>\n<p>La nuova call, che si chiuder\u00e0 il 2 aprile 2024, \u00e8 destinata a professionisti interessati a ricoprire il ruolo di professore universitario o ricercatore in diversi settori scientifico-disciplinari di area medica. Alti gli standard richiesti: elevata qualificazione scientifica e didattica, attestata da un\u2019ampia e riconosciuta attivit\u00e0 di ricerca e di produzione scientifica, nonch\u00e9 da un\u2019intensa attivit\u00e0 didattica a livello universitario o in enti di ricerca.<\/p>\n<p>Si tratta della<strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/unical-call-per-medici-professori-sono-272-altamente-specializzati-e-pronti-a-lavorare\" target=\"_blank\" rel=\"noopener\"> seconda call<\/a> di questa portata<\/strong>, che l\u2019ateneo ha scelto come modalit\u00e0 privilegiata di reclutamento da due anni a questa parte, da quando, cio\u00e8, ha attivato il corso di Medicina e chirurgia TD e ha avviato un progetto pi\u00f9 complessivo per contribuire al rilancio della sanit\u00e0 territoriale, in una regione da cui tanti medici tendono a fuggire.<\/p>\n<p>Le call, in linea con gli obiettivi programmatici del rettore Nicola Leone, si propongono di accrescere il valore competitivo dell\u2019ateneo, ampliarne i confini, rafforzare la qualit\u00e0 della didattica e della ricerca, facendo ricorso a tutti gli strumenti ministeriali per poter attrarre alte professionalit\u00e0, offrendo <strong>un posto da professore ricercatore con l\u2019opportunit\u00e0 di svolgere attivit\u00e0 assistenziale nell\u2019Azienda ospedaliera, anche nel ruolo di primario.<\/strong><\/p>\n<p>Queste manifestazioni di interessa hanno, inoltre, il valore aggiunto di richiamare molti \u201ccervelli di ritorno\u201d, calabresi validi e preparati che per mancanza di opportunit\u00e0 nella loro regione o per scelta di formazione estera hanno lasciato la loro terra, attendendo l\u2019occasione giusta per potervi fare ritorno e partecipare alla sua crescita sociale e culturale.<\/p>\n<p><strong>La prima call, lanciata un anno fa<\/strong>, ha rappresentato un punto di svolta, con un boom di circa 300 domande pervenute da tutta Italia: Milano, Napoli, Palermo, Bologna, Roma, Bergamo, solo per citarne alcune. Tra le adesioni, 55 sono state di professori universitari, 22 di primari in ospedali pubblici, 106 di dirigenti, 28 da medici in ruoli apicali nella sanit\u00e0 privata e ben 44 domande sono arrivate proprio da \u201ccervelli di ritorno\u201d. Alla fine delle procedure, nello scorso gennaio, sono stati reclutati quattro docenti medici, tre dei quali sono andati a ricoprire il ruolo di direttore di Unit\u00e0 operativa complessa rispettivamente di Oncologia, Cardiologia e Nefrologia, dialisi e trapianti presso l\u2019ospedale dell\u2019Annunziata di Cosenza.<\/p>\n<h3><strong>Leone: &#8220;l&#8217;ateneo punta a forma re nuove generazioni di\u00a0 medici&#8221;<\/strong><\/h3>\n<p>\u00abReclutando professionisti di alto profilo \u2013 ha dichiarato il rettore Nicola Leone &#8211; l&#8217;ateneo punta a formare nuove generazioni di medici sempre pi\u00f9 competenti, in grado di contrastare il problema della fuga dei camici bianchi dalla regione. Al contempo, l&#8217;arrivo di questi esperti potr\u00e0 contribuire a potenziare prestazioni di eccellenza nell\u2019Azienda ospedaliera di Cosenza, a vantaggio di tutta l&#8217;area, contribuendo a ridurre gradualmente la migrazione sanitaria\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; Cresce sempre di pi\u00f9 la squadra di docenti medici altamente qualificati che l\u2019Unical arruola per formare i futuri medici e per offrire assistenza d\u2019eccellenza nella sanit\u00e0 locale. Dopo il grande interesse mostrato da professori affermati in Italia e all\u2019estero nella precedente call, l\u2019ateneo ha deciso di aprire una nuova manifestazione di interesse [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":224689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-224687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224687"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/224689"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}