{"id":224830,"date":"2024-03-06T21:00:05","date_gmt":"2024-03-06T20:00:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224830"},"modified":"2024-03-06T20:02:04","modified_gmt":"2024-03-06T19:02:04","slug":"nuova-statale-106-tra-sibari-e-corigliano-rossano-il-progetto-sara-pubblicato-online","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/nuova-statale-106-tra-sibari-e-corigliano-rossano-il-progetto-sara-pubblicato-online\/","title":{"rendered":"Nuova statale 106 tra Sibari e Corigliano Rossano: il progetto sar\u00e0 pubblicato online"},"content":{"rendered":"<p>COSENZA &#8211; L&#8217;organizzazione di volontariato &#8220;Basta Vittime Sulla Strada Statale 106&#8221; invita tutti i cittadini a partecipare all&#8217;iniziativa <strong>&#8220;Presentazione del Progetto della Nuova Statale 106 tra Sibari e Corigliano-Rossano&#8221;<\/strong> che avr\u00e0 luogo il prossimo sabato 9 marzo presso il Centro di Eccellenza alle ore 17:00.<\/p>\n<p>&#8220;L&#8217;iniziativa nasce con l&#8217;intento di consentire, per la prima volta, a tutti i cittadini, di capire e di conoscere lo sviluppo della Grande Opera che si vuole realizzare: verr\u00e0 illustrato il tracciato, le caratteristiche pi\u00f9 importanti, le soluzioni tecniche adottate dall&#8217;Anas Spa, ecc. ecc.&#8221;, dichiara l&#8217;associazione.<\/p>\n<p>L&#8217;iniziativa nasce a seguito della <strong>pubblicazione del progetto di ammodernamento della strada Statale 106 nel tratto compreso tra Sibari e Corigliano-Rossano sul sito web della Regione Calabria<\/strong> nella sezione &#8220;Avvisi Via&#8221; ma, soprattutto, a seguito del comunicato stampa diramato dalla nostra Organizzazione di Volontariato che informava tutti i cittadini della possibilit\u00e0 di poter finalmente visionare online per la prima volta il progetto.<\/p>\n<p>Sono molti, infatti, i cittadini che hanno inviato dei messaggi alla nostra organizzazione di volontariato chiedendo di illustrare un progetto che nessuno conosce &#8211; precisato l&#8217;associazione. &#8211; Tra questi anche gli amici del &#8220;Comitato per il sottopasso&#8221; che insieme all&#8217;Organizzazione di Volontariato &#8220;Basta Vittime Sulla Strada Statale 106&#8221; ormai da giorni sono impegnati nello studio di un progetto importante che presenta certamente vantaggi ma anche criticit\u00e0 risolvibili. <strong>L&#8217;iniziativa, infine, nasce con un duplice intento:<\/strong> quello di <strong>informare i cittadini<\/strong> al fine di fargli conoscere un progetto che ignorano ma anche quello <strong>di promuovere e far nascere idee e suggerimenti<\/strong> che possano essere utili e migliorativi sul progetto in corso di realizzazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;organizzazione di volontariato &#8220;Basta Vittime Sulla Strada Statale 106&#8221; invita tutti i cittadini a partecipare all&#8217;iniziativa &#8220;Presentazione del Progetto della Nuova Statale 106 tra Sibari e Corigliano-Rossano&#8221; che avr\u00e0 luogo il prossimo sabato 9 marzo presso il Centro di Eccellenza alle ore 17:00. &#8220;L&#8217;iniziativa nasce con l&#8217;intento di consentire, per la prima volta, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":224831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-224830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224830"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/224831"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}