{"id":224864,"date":"2024-03-23T06:55:08","date_gmt":"2024-03-23T05:55:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224864"},"modified":"2024-03-23T06:55:11","modified_gmt":"2024-03-23T05:55:11","slug":"a-san-lucido-una-giornata-dedicata-allo-screening-gratuito-sullosteoporosi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a-san-lucido-una-giornata-dedicata-allo-screening-gratuito-sullosteoporosi\/","title":{"rendered":"A San Lucido una giornata dedicata allo screening gratuito sull&#8217;osteoporosi"},"content":{"rendered":"<p>SAN LUCIDO (CS) &#8211; Si intitola &#8220;Tu, sei un Osso Duro?&#8221; l&#8217;iniziativa di screening promossa da Studi Medici ARS, in localit\u00e0 Vallena sulla Statale 18 nel territorio del Comune di San Lucido.<br \/>\nSi tratta di una giornata dedicata allo screening per l&#8217;osteoporosi e alla valutazione dello stato di salute delle ossa. L&#8217;iniziativa in programma per <strong>sabato 6 aprile<\/strong>, prevede l&#8217;esecuzione di <strong>Densitometria ossea a ultrasuoni del calcagno; Valutazione propri esami ematici del metabolismo osseo se disponibili<\/strong>.<\/p>\n<p>Verr\u00e0 anche distribuito materiale informativo basato sulla prevenzione dell\u2019osteoporosi e un coupon per partecipare ad una lezione prova di ginnastica dolce\/pilates gratuita. E&#8217; richiesta la prenotazione. \u201cDedica 10 minuti alle tue Ossa, saranno il tuo sostegno per l\u2019intera vita\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN LUCIDO (CS) &#8211; Si intitola &#8220;Tu, sei un Osso Duro?&#8221; l&#8217;iniziativa di screening promossa da Studi Medici ARS, in localit\u00e0 Vallena sulla Statale 18 nel territorio del Comune di San Lucido. Si tratta di una giornata dedicata allo screening per l&#8217;osteoporosi e alla valutazione dello stato di salute delle ossa. L&#8217;iniziativa in programma per [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":224867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-224864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224864"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/224867"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}